{"id":88864,"date":"2026-05-13T07:27:10","date_gmt":"2026-05-13T10:27:10","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2026\/05\/13\/repunto-el-riesgo-pais-por-que-un-dato-economico-de-eeuu-barrio-los-avances-de-la-argentina-para-volver-a-los-mercados\/"},"modified":"2026-05-13T07:27:10","modified_gmt":"2026-05-13T10:27:10","slug":"repunto-el-riesgo-pais-por-que-un-dato-economico-de-eeuu-barrio-los-avances-de-la-argentina-para-volver-a-los-mercados","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2026\/05\/13\/repunto-el-riesgo-pais-por-que-un-dato-economico-de-eeuu-barrio-los-avances-de-la-argentina-para-volver-a-los-mercados\/","title":{"rendered":"Repunt\u00f3 el riesgo pa\u00eds: por qu\u00e9 un dato econ\u00f3mico de EEUU barri\u00f3 los avances de la Argentina para volver a los mercados"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\"visual__image image-initial-width\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/VZ5RZBRRYVCYNKBLQ34UCRQYLQ.JPG?auth=95f35aece0a1ed2ac0dcd6b6f58df6da5ae0fe55964785b4547ffc9b4004225c&amp;smart=true&amp;width=992&amp;height=661&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/VZ5RZBRRYVCYNKBLQ34UCRQYLQ.JPG?auth=95f35aece0a1ed2ac0dcd6b6f58df6da5ae0fe55964785b4547ffc9b4004225c&amp;smart=true&amp;width=768&amp;height=512&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/VZ5RZBRRYVCYNKBLQ34UCRQYLQ.JPG?auth=95f35aece0a1ed2ac0dcd6b6f58df6da5ae0fe55964785b4547ffc9b4004225c&amp;smart=true&amp;width=577&amp;height=385&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/VZ5RZBRRYVCYNKBLQ34UCRQYLQ.JPG?auth=95f35aece0a1ed2ac0dcd6b6f58df6da5ae0fe55964785b4547ffc9b4004225c&amp;smart=true&amp;width=420&amp;height=280&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/VZ5RZBRRYVCYNKBLQ34UCRQYLQ.JPG?auth=95f35aece0a1ed2ac0dcd6b6f58df6da5ae0fe55964785b4547ffc9b4004225c&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"El riesgo pa\u00eds de la Argentina volvi\u00f3 a superar los 500 puntos b\u00e1sicos tras un elevado dato de inflaci\u00f3n de Estados Unidos que sacudi\u00f3 a los mercados. REUTERS\/Brendan McDermid\" class=\"global-image\" decoding=\"async\" fetchpriority=\"high\" height=\"2862\" loading=\"eager\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/VZ5RZBRRYVCYNKBLQ34UCRQYLQ.JPG?auth=95f35aece0a1ed2ac0dcd6b6f58df6da5ae0fe55964785b4547ffc9b4004225c&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"4293\"\/><\/picture><figcaption class=\"article-figcaption-img\">El riesgo pa\u00eds de la Argentina volvi\u00f3 a superar los 500 puntos b\u00e1sicos tras un elevado dato de inflaci\u00f3n de Estados Unidos que sacudi\u00f3 a los mercados. REUTERS\/Brendan McDermid<\/figcaption><\/div>\n<p class=\"paragraph\">Se dispar\u00f3 la <b>inflaci\u00f3n en Estados Unidos<\/b><b> <\/b>y contagi\u00f3 al resto del planeta. El \u00edndice de precios de abril fue de <b>3,8% interanual<\/b>, un porcentaje m\u00e1s elevado que el c\u00e1lculo del analista m\u00e1s pesimista de EE.UU.<\/p>\n<p class=\"paragraph\">Los<b> combustibles<\/b> fueron m\u00e1s inflamables que nunca y fueron los responsables de 40% del \u00edndice. Desde el comienzo de la guerra del Golfo, la nafta en territorio estadounidense aument\u00f3 50% y el gasoil, 100 por ciento.<\/p>\n<p class=\"paragraph\">Todos los mercados levantaron el pie del acelerador para no asumir riesgos. El conflicto en Medio Oriente no tiene soluci\u00f3n cercana y <b>los inversores temen que sus activos pierdan terreno<\/b>. Las conversaciones siguen estancadas y no hay un patr\u00f3n de conducta en los contendientes que pueda definir lo que suceder\u00e1 al d\u00eda siguiente. La guerra y la paz est\u00e1n juntas y a la vuelta de la esquina, esperando una se\u00f1al. <\/p>\n<p class=\"paragraph\">En la regi\u00f3n, el \u00edndice de emergentes perdi\u00f3 m\u00e1s de 3% y l<b>a Argentina vio como se le esfumaba el enorme logro de bajar el riesgo pa\u00eds a menos de 500 puntos b\u00e1sicos<\/b>. Los bonos soberanos rebotaron a entre 1,1 y 2% en los plazos m\u00e1s largos y el indicador elaborado por JP Morgan aument\u00f3 15 unidades (3%) a <b>511 enteros<\/b>.<\/p>\n<p class=\"paragraph\">Tambi\u00e9n cay\u00f3 la Bolsa: El <b>S&amp;P Merval <\/b>de las acciones l\u00edderes cedi\u00f3 1,4% en pesos y 1,1% en d\u00f3lares acompa\u00f1ando a las Bolsas de Nueva York que cedieron hasta 0,71 por ciento.<\/p>\n<p class=\"paragraph\">Seg\u00fan <b>Inversiones Pergamino<\/b> \u201c<b>no hay estr\u00e9s, pero s\u00ed una pausa clara para los activos argentinos<\/b>. La clave es que el contexto externo no rompa el flujo y que el mercado local logre sostener soportes para volver a intentar el quiebre de los USD 2.000. El Merval y los activos argentinos no se mueven \u00fanicamente por balances, producci\u00f3n o resultados corporativos\u201d. <\/p>\n<p class=\"paragraph\">\u201cEn la Argentina, el mercado tambi\u00e9n cotiza pol\u00edtica, y mucho. Existen dos grandes tipos de participantes: <i>traders<\/i> e inversores. Los <i>traders<\/i> operan el presente y los inversores compran futuro. Y son justamente estos \u00faltimos quienes terminan definiendo las grandes tendencias del mercado. Porque el inversor no espera a que los cambios ocurran; intenta adelantarse a\u00f1os. Ah\u00ed aparece una de las variables m\u00e1s importantes: no solo importa qu\u00e9 puede hacer este gobierno durante su mandato, sino tambi\u00e9n qu\u00e9 podr\u00eda ocurrir despu\u00e9s. <b>El mercado ya empieza a mirar el per\u00edodo 2027-2031<\/b>\u201d, acota el informe.<\/p>\n<p class=\"paragraph\">En tanto, en el <b>Mercado Libre de Cambios<\/b> (MLC) se operaron USD 447 millones y el<b> <\/b><b>Banco Central<\/b><b> compr\u00f3 USD 70 millones<\/b> que elevaron las reservas en USD 42 millones a 46.185 millones de d\u00f3lares. El d\u00f3lar mayorista baj\u00f3 $7,50 (-0,5%) a 1.384 pesos.<\/p>\n<p class=\"paragraph\">En la plaza financiera el MEP cedi\u00f3 $6,15 (-0,4%) a $1.419 y el contado con liquidaci\u00f3n (CCL) baj\u00f3 $4,10 (-0,3%) a 1.476 pesos. El \u201cblue\u201d subi\u00f3 $10 a 1.415 pesos.<\/p>\n<p class=\"paragraph\">En paralelo, tambi\u00e9n<b> subi\u00f3 el precio del petr\u00f3leo <\/b>e incidir\u00e1 en la futura inflaci\u00f3n de la Argentina. El Brent cerr\u00f3 ayer 3,5% arriba a 107,45 d\u00f3lares por barril.<\/p>\n<p class=\"paragraph\"><b>Matias Togni<\/b> analista de la consultora petrolera <b>NextBarrel<\/b> se\u00f1al\u00f3 que \u201cel mercado del petr\u00f3leo se dio vuelta y hoy nos encontramos en la situaci\u00f3n inversa a marzo, donde los futuros valen m\u00e1s que el barril f\u00edsico. En el corto plazo hubo una especie de sobre oferta en occidente porque China decidi\u00f3 retraer las compras para junio, haciendo uso de sus reservas estrat\u00e9gicas dejando un vac\u00edo en la demanda\u201d. <\/p>\n<p class=\"paragraph\">\u201cEn los futuros, el ojo est\u00e1 puesto en la reuni\u00f3n de Donald Trump con Xi Jinping de ma\u00f1ana (por hoy) y aunque no se espera que salga nada significativo de ah\u00ed, tal vez el tono de China cambie y se vea m\u00e1s dispuesto a presionar a Ir\u00e1n, porque m\u00e1s all\u00e1 del suministro energ\u00e9tico, los n\u00fameros de la econom\u00eda china empiezan a preocupar. Nadie est\u00e1 exento, ni siquiera nosotros que aguardamos <b>la decisi\u00f3n de YPF respecto de los combustibles que<\/b>, dicho sea de paso, est\u00e1n m\u00e1s altos que cuando se decidi\u00f3 congelarlos\u201d, evalu\u00f3 Togni.<\/p>\n<p class=\"paragraph\"><b>Dami\u00e1n Vlassich<\/b>,<i> team leader<\/i> de Estrategias de Inversi\u00f3n en <b>IOL<\/b>, cree que tras estos datos se \u201ccomplica el escenario de baja de tasas para el nuevo presidente de la Reserva Federal, <b>Kevin Warsh<\/b>. La energ\u00eda represent\u00f3 m\u00e1s del 40% del incremento y puso el clavo en el ata\u00fad de las esperanzas de una baja de tasas inminente\u201d. <\/p>\n<p class=\"paragraph\">Las tasas de inter\u00e9s en pesos siguieron bajando, pero solo hasta fin de octubre. Las LECAP en ese lapso pagan entre 1,7% y 1,9% efectivo mensual, al tiempo que continu\u00f3 el alza de los bonos CER.<\/p>\n<p class=\"paragraph\">F2, la consultora que dirige <b>Andr\u00e9s Reschini<\/b>,<b> <\/b>destac\u00f3 que \u201cen lo que va de mayo, la tendencia del volumen de liquidaciones sigue a la baja lo que podr\u00eda estar motivado por una tendencia a la retenci\u00f3n por parte de los productores agropecuarios a la espera de mejores condiciones, afectados por m\u00e1rgenes ajustados\u201d.<\/p>\n<p class=\"paragraph\">El reporte agrega que \u201clos dep\u00f3sitos del Gobierno en el BCRA en moneda extranjera se ubican en USD 533 millones (al 08 de mayo) luego del pago al FMI. El importe es similar a lo que resta cancelar dentro de mayo por lo que seguimos muy justos en ese sentido. Este mi\u00e9rcoles (por hoy) el Tesoro intentar\u00e1 hacerse de otros USD 500 millones mediante colocaci\u00f3n del AO27 y AO28 mientras que los compromisos a afrontar en los pr\u00f3ximos dos meses seg\u00fan la OPC (Oficina de Presupuesto del Congreso) ascienden a los USD 5.338 millones. Los dep\u00f3sitos en pesos al tipo de cambio oficial equivalen a USD 6.000 millones, con lo que el Tesoro tiene poder de fuego para reforzar sus tenencias en caso de que los pr\u00e9stamos y privatizaciones no sean suficientes, a expensas de reservas del BCRA\u201d.<\/p>\n<p class=\"paragraph\">El<b> clima para hoy puede ser mejor<\/b> porque las Bolsas neoyorquinas no ten\u00edan una tendencia definida y el petr\u00f3leo operaba con leves bajas. El oro estaba en alza de casi 1% y el d\u00f3lar segu\u00eda en leve aumento. Pero de aqu\u00ed al mediod\u00eda hay una eternidad. El estilo intempestivo de las canciller\u00edas estadounidense e iran\u00ed modifica el humor de los mercados en minutos. El problema, y lo \u00fanico que sirve de referencia, es que el <b>estrecho de Ormuz sigue cerrado<\/b>. <\/p>\n<\/div>\n<p><script defer=\"\">try{!function(f,b,e,v,n,t,s) {if(f.fbq)return;n=f.fbq=function(){n.callMethod? n.callMethod.apply(n,arguments):n.queue.push(arguments)}; if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0'; n.queue=[];t=b.createElement(e);t.async=!0; t.src=v;s=b.getElementsByTagName(e)[0]; s.parentNode.insertBefore(t,s)}(window, document,'script', ' fbq('init', '336383993555320'); fbq('track', 'PageView'); fbq('track', 'ViewContent');}catch(error){console.log(\"Error al inicializar facebookPixelRawCodeScript:\",error);}<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El riesgo pa\u00eds de la Argentina volvi\u00f3 a superar los 500 puntos b\u00e1sicos tras un elevado dato de inflaci\u00f3n de Estados Unidos que sacudi\u00f3 a los mercados. REUTERS\/Brendan McDermid Se dispar\u00f3 la inflaci\u00f3n en Estados Unidos y contagi\u00f3 al resto del planeta. El \u00edndice de precios de abril fue de 3,8% interanual, un porcentaje m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":87471,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/88864"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=88864"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/88864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/87471"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=88864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=88864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=88864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}