{"id":87020,"date":"2026-04-15T17:42:08","date_gmt":"2026-04-15T20:42:08","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2026\/04\/15\/lidero-una-mitica-banda-de-los-80-marco-para-siempre-a-los-que-lo-vieron-y-a-los-que-tocaron-con-el-y-murio-tragicamente-a-los-30-anos\/"},"modified":"2026-04-15T17:42:08","modified_gmt":"2026-04-15T20:42:08","slug":"lidero-una-mitica-banda-de-los-80-marco-para-siempre-a-los-que-lo-vieron-y-a-los-que-tocaron-con-el-y-murio-tragicamente-a-los-30-anos","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2026\/04\/15\/lidero-una-mitica-banda-de-los-80-marco-para-siempre-a-los-que-lo-vieron-y-a-los-que-tocaron-con-el-y-murio-tragicamente-a-los-30-anos\/","title":{"rendered":"Lider\u00f3 una m\u00edtica banda de los 80, marc\u00f3 para siempre a los que lo vieron y a los que tocaron con \u00e9l y muri\u00f3 tr\u00e1gicamente a los 30 a\u00f1os"},"content":{"rendered":"<p><\/p>\n<div>\n<p class=\"com-paragraph  --capital --s\">Nunca le gust\u00f3 tocar \u201cpara la gente\u201d: varias veces, en el escenario, se pon\u00eda de espaldas al p\u00fablico con su guitarra. Esquivo y de pocas palabras, <strong>Hern\u00e1n Darwin Reyna<\/strong> sent\u00eda la m\u00fasica como algo m\u00e1s personal, \u00edntimo. Sus amigos sab\u00edan que no deseaba que se convirtiera en un sustento econ\u00f3mico y, menos a\u00fan, quer\u00eda ser famoso. No le gustaba el estrellato ni ser el principal protagonista de su banda. Era t\u00edmido, pero con mucho sentido del humor. Era cari\u00f1oso, pero enigm\u00e1tico, huidizo. <\/p>\n<p class=\"com-paragraph   --s\">No ten\u00eda un manager ni productor. <strong>El Corte<\/strong> tocaba en teatros y centros culturales, no en pubs ni en bares. No quer\u00edan que sus canciones sonaran en las radios e, incluso, iban personalmente a los programas para impedirlo. \u201cMe impact\u00f3 la m\u00fasica de El Corte, en los 80, especialmente la voz y la l\u00edrica de Hern\u00e1n Reyna. A partir de ah\u00ed quise saber m\u00e1s porque me llamaba la atenci\u00f3n que hubiera sacado dos discos tan buenos y hubiera desaparecido como lo hizo\u201d, dice el periodista, m\u00fasico y director de la revista <strong>Rolling Stone<\/strong> en su edici\u00f3n Argentina, <strong>Daniel Flores<\/strong>, coautor junto a <strong>Mart\u00edn Wain<\/strong> del documental <em><strong>El camino contrario<\/strong><\/em>, que se estrenar\u00e1 en el <strong>Bafici<\/strong> este s\u00e1bado 18, a las 23, en Cin\u00e9polis Plaza Houssay, con entradas agotadas. Tendr\u00e1 una segunda funci\u00f3n en el festival de cine el jueves 23, a las 17, en Cin\u00e9polis Recoleta, Sala 3. A\u00fan quedan entradas y se pueden adquirir en <em>entradasba.buenosaires.gob.ar<\/em>.<\/p>\n<p><iframe loading=\"lazy\" title=\"Trailer El camino contrario\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/knvgCOUcBFE?wmode=transparent&amp;rel=0&amp;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p class=\"com-paragraph   --s\">Sin ir m\u00e1s lejos, as\u00ed es como el grupo de postpunk y tambi\u00e9n de rock psicod\u00e9lico y g\u00f3tico, uno de los secretos mejores guardados de la m\u00fasica popular argentina, hab\u00eda llamado a su segundo disco: <em>El camino contrario<\/em>, grabado en 1987. Sus integrantes coinciden en el documental que \u201cse escuch\u00f3 m\u00e1s luminoso, ordenado y rockero\u201d que su primer lanzamiento, <em>El Corte<\/em>, grabado un a\u00f1o antes en una larga noche fr\u00eda e invernal en una usina gigante de Segba, por entonces la empresa p\u00fablica de electricidad de Buenos Aires. <\/p>\n<p class=\"com-paragraph   --s\">El grupo, formado por <strong>Javier Calamaro<\/strong> (voz, bater\u00eda, teclados y guitarra), <strong>Hern\u00e1n Darwin Reyna<\/strong> (guitarras y voz), <strong>Federico Oldemburg<\/strong> (teclados), <strong>Pablo Mart\u00edn<\/strong> (bajo) y <strong>Leonardo Ramella<\/strong> (bater\u00eda y teclados) se hab\u00eda creado en 1986, y tras esos dos discos y una serie de presentaciones en vivo, se separ\u00f3 en 1988: fueron dos a\u00f1os agitados, abruptos, de un \u201cduelo\u201d que todos los miembros -menos Reyna, que muri\u00f3 ahogado en el mar Mediterr\u00e1neo en 1994-, reunidos para el audiviosual reconocen que, de alg\u00fan modo, hab\u00eda estado pendiente.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">El camino contrario<\/span><span class=\"com-text --credit --twoxs\">Prensa Bafici<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">\u201cDaniel Santos hab\u00eda escrito un cap\u00edtulo del libro <em>Gente que no<\/em> dedicado a El Corte y a Hern\u00e1n. Apenas lo le\u00ed, le propuse pensar un documental para hacer juntos, porque era una historia que necesitaba ser contada. Para rescatar la figura de un talento como Hern\u00e1n y para que se volviera a escuchar la m\u00fasica de El Corte\u201d, reconstruye el tambi\u00e9n periodista y docente, Mart\u00edn Wain, sobre la g\u00e9nesis del film. Wain ya ten\u00eda experiencia audiovisual, con varios cortos de ficci\u00f3n y documentales, y adem\u00e1s form\u00f3 parte del equipo de guion de <em>El Eternauta<\/em>. <\/p>\n<p class=\"com-paragraph   --s\">El proceso de investigaci\u00f3n dur\u00f3 largos a\u00f1os, y descubrieron el atractivo de Hern\u00e1n Reya como un personaje muy particular, a tono con su m\u00fasica. Pero, a la vez, incluso m\u00e1s complejo que su m\u00fasica. \u201cLos discos de El Corte pueden ubicarse en la batea de postpunk o incluso g\u00f3tico. Y, sin embargo, no son s\u00f3lo eso ni son clich\u00e9 ni banales. Es m\u00fasica con muchas capas, y Hern\u00e1n tambi\u00e9n era as\u00ed\u201d, sintetiza Flores.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">El camino contrario<\/span><span class=\"com-text --credit --twoxs\">Prensa Bafici<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">Antes que El Corte, Reyna hab\u00eda formado parte de bandas juveniles, como Zaratustra y Frapp\u00e9. Hay filmaciones en s\u00faper 8. \u201cHern\u00e1n era un bicho raro, medio antisocial\u201d, dice <strong>Kevin Johansen<\/strong>, que comparti\u00f3 juventud con \u00e9l. <strong>Sergio Rotman<\/strong> trabajaba en una disquer\u00eda. Mariela, la hermana de Hern\u00e1n, lo hac\u00eda en un videoclub, a pocas cuadras. Ella le pregunt\u00f3 si conoc\u00eda un saxofonista para la banda de Hern\u00e1n. Luego, Sergio convoc\u00f3 a Pablo Mart\u00edn. Como periodista de Pelo, Federico Oldemburg fue a cubrir un recital de Frapp\u00e9. Les peg\u00f3 con un ca\u00f1o. Javier Calamaro lo llam\u00f3 por tel\u00e9fono. \u201cEstoy totalmente de acuerdo con vos\u201d, le dijo, sorpresivamente, y luego: \u201c\u00bfToc\u00e1s alg\u00fan instrumento?\u201d. Y as\u00ed, de forma azarosa y casera, Frapp\u00e9 dio nacimiento a El Corte. <\/p>\n<p class=\"com-paragraph   --s\">Adem\u00e1s de secretos y huecos en la historia, hab\u00eda muchos enigmas alrededor de la figura de Hern\u00e1n. Algunos se develaron en la pel\u00edcula; otros quedaron abiertos, flotando en la interpretaci\u00f3n de sus canciones, \u201catravesadas por im\u00e1genes del agua y las profundidades\u201d, seg\u00fan los directores. \u201cEra, adem\u00e1s, un m\u00fasico contrario a la fama: nada m\u00e1s lejos de un <em>rockstar<\/em> y, al mismo tiempo, due\u00f1o de un gran magnetismo\u201d, lo define Wain. <\/p>\n<p class=\"com-paragraph   --s\">Para varios entrevistados, la suya fue la mejor voz del rock argentino. Entre las proezas, se reconstruye c\u00f3mo fue la grabaci\u00f3n del primer disco en aquel galp\u00f3n de Segba, al mando del ingeniero de sonido <strong>Mario Breuer<\/strong>, que aprovech\u00f3 \u201cuna c\u00e1mara natural\u201d para dise\u00f1ar un sonido claustrof\u00f3bico, herrumbroso, con efectos de ruidos ambientales y la crudeza de lo dark. Lo grabaron de noche, para que no se filtrara el ruido de los colectivos. \u201cNo me pregunten c\u00f3mo, pero funcion\u00f3\u201d, se r\u00ede Breuer, que mont\u00f3 un estudio en el descomunal galp\u00f3n en menos de veinte horas. <\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">Hern\u00e1n Darwin Reyna<\/span><span class=\"com-text --credit --twoxs\">Prensa Bafici<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">\u201cEn la banda, Hern\u00e1n tocaba menos de lo que pod\u00eda tocar, pero le sobraba\u201d, dice el saxofonista Sergio Rotman, que lo coloca al lado de \u201cGamexane\u201d Villafa\u00f1e, de Todos Tus Muertos, como una de las voces destacadas del punk argentino. \u201cLos discos fueron incre\u00edbles, pero no hay nostalgia de aquella \u00e9poca, que era fea y oscura\u201d, agrega. <\/p>\n<p class=\"com-paragraph   --s\">El Corte grab\u00f3 su primer disco sin tocar en vivo previamente: tan s\u00f3lo era una cuesti\u00f3n de presupuesto. Otros testimonios celebran la inflexi\u00f3n de su canto en temas como \u201cDesgarra la carne cl\u00e9riga\u201d, suerte de voz de \u00e1ngel en un marco sonoro infernal. La fot\u00f3grafa <strong>Andy Cherniavsky<\/strong> repasa su archivo. Los shows de El Corte sol\u00edan ser fr\u00edos: los m\u00fasicos no quer\u00edan que el p\u00fablico aplaudiera. Se recuerda el primer concierto en La Manzana de las Luces, otros en el San Mart\u00edn y despu\u00e9s en el Recoleta. <\/p>\n<p class=\"com-paragraph   --s\">\u201cLa vida en torno al grupo era como la de una familia: cocin\u00e1bamos, nos hac\u00edamos chistes. En lo cotidiano ellos eran tranquilos, comunes, y se transformaban cuando se pon\u00edan a tocar, con la m\u00fasica densa, dark, irradiando en el ambiente. Pero no era impostado, les sal\u00eda art\u00edsticamente\u201d, dice Andy. <\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">El Corte en tiempos de &#8220;raros peinados nuevos&#8221;<\/span><span class=\"com-text --credit --twoxs\">Prensa Bafici<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">\u201cLo nuestro era caos y confusi\u00f3n en un mundo donde hab\u00eda tambores, beat y glam\u201d, repasa Javier Calamaro y subraya: \u201cPrefer\u00edamos los lugares antro, con la luminosidad de lo creativo de los ochenta y, por otro lado, lo oscuro de la est\u00e9tica punk\u201d. \u201cPrimero vinieron Virus, Los Abuelos de la Nada, Los Twist y despu\u00e9s el clima se puso pesado y pesimista. La democracia no era la panacea, se respiraban a\u00f1os violentos, con la hiperinflaci\u00f3n a punto de estallar\u201d, reconstruye Ariel Minimal en el documental, que fue filmado entre Argentina y Espa\u00f1a. <\/p>\n<p class=\"com-paragraph   --s\">El guion se fue modificando con la investigaci\u00f3n y se termin\u00f3 de definir con la participaci\u00f3n de <strong>Eliane Katz<\/strong> en el montaje. \u201cCuando se cuenta aquella \u00e9poca \u2013de mediados de los 80 a comienzos de los 90\u2013 suelen nombrarse sus expresiones m\u00e1s consagradas: Virus, Soda Stereo, Los Abuelos de la Nada, Sumo o Patricio Rey y sus Redonditos de Ricota. Poco se ha retratado a las bandas como El Corte. Porque as\u00ed como la primavera alfonsinista fue un per\u00edodo floreciente para la cultura joven, la crisis econ\u00f3mica interrumpi\u00f3 otros movimientos, los dej\u00f3 truncos o los expuls\u00f3, mientras los pibes de crestas y ojos pintados se llevaban la peor parte de un sistema represivo que no hab\u00eda cambiado demasiado desde la dictadura\u201d, remarcan los autores. <\/p>\n<p class=\"com-paragraph   --s\">Todos tomaban coca\u00edna. \u201cNo hay que tomar m\u00e1s. Si segu\u00eds tomando, me voy\u201d, le dijo Hern\u00e1n a su novia de entonces, la artista Nushi Muntaabski, y poco despu\u00e9s agarr\u00f3 los bolsos y sus instrumentos de sonido y se fue de la casa. \u201cHern\u00e1n no ten\u00eda medida, era imposible sujetarlo. Lo echaron de los colegios donde estuvo. Era frontal, dec\u00eda lo que sent\u00eda y pagaba las consecuencias\u201d, cuenta <strong>Mariela Reyna<\/strong>, su hermana, con la que vivi\u00f3 un tiempo y luego, en su temporada en Europa, sigui\u00f3 escribi\u00e9ndose cartas. <\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">Javier Calamaro, compa\u00f1ero de Hern\u00e1n Reyna en Frapp\u00e9 y El Corte<\/span><span class=\"com-text --credit --twoxs\">Prensa Bafici<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">Los m\u00fasicos de la banda concuerdan que el segundo disco, <em>El camino contrario<\/em>, son\u00f3 m\u00e1s limpio y ortodoxo, sin la influencia de las drogas duras. Hay una foto de Hern\u00e1n con la mirada hacia el suelo, en pose contemplativa: un gesto habitual en \u00e9l. <\/p>\n<p class=\"com-paragraph   --s\">Despu\u00e9s de la separaci\u00f3n de El Corte, Hern\u00e1n viaja a Alemania. Vive con su novia en una especie de s\u00f3tano, con poco dinero. No hace otra cosa que tocar la guitarra. Arma un estudio de grabaci\u00f3n. Pero estaba sin documentos, no pod\u00eda moverse libremente. No encaja con la cultura alemana. <\/p>\n<p class=\"com-paragraph   --s\">Se casa, con su pareja se radican en Madrid. A sus amigos les manda videos desde Espa\u00f1a: se lo ve en movidas creativas, pero no habla. Lo notan feliz. Logra armarse otro estudio. Se junta con Ariel Rot, Daniel Santamar\u00eda, Federico Oldemburg. \u201cSiempre ten\u00eda en mente grabar un nuevo disco, pero no quer\u00eda tocar en vivo. Incorpor\u00f3 una riqueza de sonido y un ritmo m\u00e1s rockero que El Corte. En Madrid era una buena \u00e9poca para la m\u00fasica y \u00e9l era un talento \u00fanico, singular\u201d, dice Oldemburg.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" tabindex=\"0\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">El lugar en el que Hern\u00e1n Reyna perdi\u00f3 su vida, en el mar Mediterr\u00e1neo<\/span><span class=\"com-text --credit --twoxs\">Prensa Bafici<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">Entr\u00f3 en una etapa obsesiva. Cre\u00f3 un modus operandi alrededor del estudio donde cab\u00edan sus conexiones, todas sus relaciones. \u201cDesde el s\u00f3tano al mundo\u201d, dice Sol, su novia de entonces. Con todo el equipaje en una mochila, se fueron a vivir a una especie de monumento, cerca del Mediterr\u00e1neo. Disfrutaba de una casa con molino: a Hern\u00e1n se lo notaba m\u00e1s sonriente, con mejor color, m\u00e1s relajado, m\u00e1s suelto, ya no estaba tan encerrado con su guitarra. \u201cUna relaci\u00f3n puro presente, sin mucho hablar de pasado, sin mucho futuro. Instante, s\u00f3lo instante\u201d, enfatiza Sol. <\/p>\n<p class=\"com-paragraph   --s\">Ten\u00edan ahorros, pensaban comprar una casa. No ten\u00eda m\u00e1s que su guitarra y su voz pero le faltaba un proyecto musical en Madrid. Hern\u00e1n Reyna, en efecto, quer\u00eda construir un nuevo presente. El destino lo encontr\u00f3 en la costa de <strong>J\u00e1vea<\/strong>. Un paseo, el lugar maravilloso, una cueva, la luz azul, y la desesperaci\u00f3n de una barca que se hunde y \u00e9l, sin saber nadar, con un pesado abrigo a cuestas, que encuentra la fatalidad, parad\u00f3jicamente en uno de los mejores momentos de su vida a sus j\u00f3venes treinta a\u00f1os. La marea hab\u00eda pasado de la calma a la tempestad, en cuesti\u00f3n de minutos. Lo socorrieron, hasta que dos o tres olas lo arrastraron lejos. \u201cCre\u00eda que todav\u00eda estaba ah\u00ed, flotando\u201d, recuerda Sol. <\/p>\n<p class=\"com-paragraph   --s\">\u201cHern\u00e1n fue un enigma. Lo que compuso. Lo que guardaba adentro. Lo que surg\u00eda de su guitarra. Lo que escrib\u00eda en las cartas. \u00bfC\u00f3mo reunimos a todas esas personas en una? Siempre fue un pibe s\u00faper especial, que nadie sab\u00eda en qu\u00e9 mundo estaba o cu\u00e1l era su realidad concreta\u201d, acota su hermana. <\/p>\n<p class=\"com-paragraph   --s\">Se lo enterr\u00f3 en Espa\u00f1a con una guitarra, sus amigos lo celebraron en una fiesta. Algunos de los temas que dej\u00f3 in\u00e9ditos fueron recuperados mucho tiempo despu\u00e9s de su muerte, en 2022, y se publicaron en CD por el sello Mucha Madera. Una de sus notables creaciones, El Corte, se rescata en el film como la banda postpunk de los ochenta en Buenos Aires que pocos escucharon y casi nadie vio tocar en vivo, pero que marc\u00f3 para siempre a quienes s\u00ed lo hicieron. <\/p>\n<section class=\"container-center-100 mb-40 border border-bottom border-thin border-neutral-light-700\">\n<hr\/>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nunca le gust\u00f3 tocar \u201cpara la gente\u201d: varias veces, en el escenario, se pon\u00eda de espaldas al p\u00fablico con su guitarra. Esquivo y de pocas palabras, Hern\u00e1n Darwin Reyna sent\u00eda la m\u00fasica como algo m\u00e1s personal, \u00edntimo. Sus amigos sab\u00edan que no deseaba que se convirtiera en un sustento econ\u00f3mico y, menos a\u00fan, quer\u00eda ser [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":87021,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87020"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=87020"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/87021"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=87020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=87020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=87020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}