{"id":85750,"date":"2026-04-09T13:52:03","date_gmt":"2026-04-09T16:52:03","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2026\/04\/09\/florencio-varela-asesinaron-a-tiros-a-una-jubilada-de-80-anos-durante-una-entradera\/"},"modified":"2026-04-09T13:52:03","modified_gmt":"2026-04-09T16:52:03","slug":"florencio-varela-asesinaron-a-tiros-a-una-jubilada-de-80-anos-durante-una-entradera","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2026\/04\/09\/florencio-varela-asesinaron-a-tiros-a-una-jubilada-de-80-anos-durante-una-entradera\/","title":{"rendered":"Florencio Varela: asesinaron a tiros a una jubilada de 80 a\u00f1os durante una entradera"},"content":{"rendered":"<p><\/p>\n<h2 class=\"article-subheadline text_align_left\">Ocurri\u00f3 anoche en la localidad de Zeballos. La v\u00edctima, identificada como Flora Ignacia Ben\u00edtez, fue hallada sin vida por sus familiares<\/h2>\n<p><\/p>\n<p class=\"paragraph\"><b>Una jubilada de 79 a\u00f1os <\/b>fue asesinada a tiros durante la noche de este mi\u00e9rcoles por un grupo de delincuentes que irrumpi\u00f3 en su domicilio de la localidad de Zeballos, partido bonaerense de <i><b>Florencio Varela<\/b><\/i>, mientras descansaba y <b>en medio de un corte de luz<\/b> repentino que afect\u00f3 a la zona. <\/p>\n<p><\/p>\n<p class=\"paragraph\">De acuerdo a la reconstrucci\u00f3n que lograron realizar los investigadores de la DDI Quilmes de la Polic\u00eda Bonaerense, a cargo de la investigaci\u00f3n, Ben\u00edtez descansaba en su casa cuando <b>advirti\u00f3 la presencia de varios hombres que intentaban ingresar.<\/b><\/p>\n<p><\/p>\n<p class=\"paragraph\">En ese momento, se produjo un intercambio de disparos y uno de los proyectiles impact\u00f3 en el t\u00f3rax de la mujer, que muri\u00f3 casi de inmediato.<\/p>\n<p><\/p>\n<p class=\"paragraph\">Familiares de la v\u00edctima alertaron al 911. Al arribar al lugar del hecho, el<b> <\/b>personal policial hall\u00f3 a Ben\u00edtez tendida en el living de la vivienda, mientras que sobre una de las ventanas del frente se observaron <b>m\u00faltiples impactos de bala<\/b>. <\/p>\n<p><\/p>\n<p class=\"paragraph\">Los autores del hecho escaparon en dos camionetas y permanecen pr\u00f3fugos. Hasta el momento, la investigaci\u00f3n no registr\u00f3 detenciones y la causa sigue abierta, bajo la intervenci\u00f3n de la UFI N\u00b0 2 Descentralizada de Florencio Varela, a cargo del <b>fiscal Federico Pagliuca<\/b>.<\/p>\n<p><\/p>\n<p class=\"paragraph\"><i>Noticia en desarrollo<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ocurri\u00f3 anoche en la localidad de Zeballos. La v\u00edctima, identificada como Flora Ignacia Ben\u00edtez, fue hallada sin vida por sus familiares Una jubilada de 79 a\u00f1os fue asesinada a tiros durante la noche de este mi\u00e9rcoles por un grupo de delincuentes que irrumpi\u00f3 en su domicilio de la localidad de Zeballos, partido bonaerense de Florencio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":85751,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/85750"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=85750"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/85750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/85751"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=85750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=85750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=85750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}