{"id":77940,"date":"2026-02-07T05:43:02","date_gmt":"2026-02-07T08:43:02","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2026\/02\/07\/estados-unidos-anuncio-nuevos-aranceles-adicionales-para-los-paises-que-comercien-con-el-regimen-irani\/"},"modified":"2026-02-07T05:43:02","modified_gmt":"2026-02-07T08:43:02","slug":"estados-unidos-anuncio-nuevos-aranceles-adicionales-para-los-paises-que-comercien-con-el-regimen-irani","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2026\/02\/07\/estados-unidos-anuncio-nuevos-aranceles-adicionales-para-los-paises-que-comercien-con-el-regimen-irani\/","title":{"rendered":"Estados Unidos anunci\u00f3 nuevos aranceles adicionales para los pa\u00edses que comercien con el r\u00e9gimen iran\u00ed"},"content":{"rendered":"<p><\/p>\n<div xmlns:default=\"http:\/\/www.w3.org\/2000\/svg\">\n<div class=\"visual__image image-initial-width\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/RYIJZU4J7NFLZL5U74LRPCTXB4.jpg?auth=9f89f7fa52f829f62a743d676f8e4877a6c4405d0691de6e8880651d3a85c15f&amp;smart=true&amp;width=992&amp;height=661&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/RYIJZU4J7NFLZL5U74LRPCTXB4.jpg?auth=9f89f7fa52f829f62a743d676f8e4877a6c4405d0691de6e8880651d3a85c15f&amp;smart=true&amp;width=768&amp;height=512&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/RYIJZU4J7NFLZL5U74LRPCTXB4.jpg?auth=9f89f7fa52f829f62a743d676f8e4877a6c4405d0691de6e8880651d3a85c15f&amp;smart=true&amp;width=577&amp;height=385&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/RYIJZU4J7NFLZL5U74LRPCTXB4.jpg?auth=9f89f7fa52f829f62a743d676f8e4877a6c4405d0691de6e8880651d3a85c15f&amp;smart=true&amp;width=420&amp;height=280&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/RYIJZU4J7NFLZL5U74LRPCTXB4.jpg?auth=9f89f7fa52f829f62a743d676f8e4877a6c4405d0691de6e8880651d3a85c15f&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"EEUU anunici\u00f3 nuevos aranceles a\" class=\"global-image\" decoding=\"async\" fetchpriority=\"high\" height=\"1280\" loading=\"eager\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/RYIJZU4J7NFLZL5U74LRPCTXB4.jpg?auth=9f89f7fa52f829f62a743d676f8e4877a6c4405d0691de6e8880651d3a85c15f&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"1920\"\/><\/picture><figcaption class=\"article-figcaption-img\">EEUU anunici\u00f3 nuevos aranceles a pa\u00edses que comercien con Ir\u00e1n (Europa Press)<\/figcaption><\/div>\n<p class=\"paragraph\">El presidente estadounidense, <b>Donald Trump<\/b>, anunci\u00f3 la imposici\u00f3n de un <b>arancel adicional a los productos de pa\u00edses que mantengan v\u00ednculos comerciales con el r\u00e9gimen de Ir\u00e1n<\/b>, argumentando que \u201clas acciones y pol\u00edticas del gobierno iran\u00ed <b>constituyen una amenaza inusual y extraordinaria para la seguridad nacional<\/b>, la pol\u00edtica exterior y la econom\u00eda de Estados Unidos\u201d.<\/p>\n<p class=\"paragraph\">Seg\u00fan el comunicado emitido por la Casa Blanca, el nuevo gravamen <b>\u201cad valorem\u201d <\/b>adicional <b>se aplicar\u00e1 a las importaciones procedentes de pa\u00edses extranjeros que compren, importen o adquieran, directa o indirectamente, bienes o servicios de Ir\u00e1n<\/b>.<\/p>\n<p class=\"paragraph\">Trump defendi\u00f3 que este r\u00e9gimen arancelario permitir\u00e1 abordar \u201cde manera m\u00e1s eficaz la emergencia nacional\u201d declarada en la Orden Ejecutiva 12957 de 1995 sobre Ir\u00e1n.<\/p>\n<p class=\"paragraph\">El secretario de Comercio ser\u00e1 responsable de determinar si un tercer pa\u00eds adquiri\u00f3 bienes o servicios iran\u00edes, y deber\u00e1 notificarlo al secretario de Estado con la informaci\u00f3n pertinente.<\/p>\n<p class=\"paragraph\">El encargado de la cartera comercial estadounidense podr\u00e1 emitir normas y directrices para la aplicaci\u00f3n de esta pol\u00edtica, y elaborar\u00e1 un informe para que el titular del Departamento de Estado decida \u2014tras consultar a otros departamentos\u2014 si corresponde imponer el arancel adicional y en qu\u00e9 medida.<\/p>\n<p class=\"paragraph\"><b>La orden presidencial otorga al secretario de Estado la facultad de implementar regulaciones y tomar cualquier otra medida necesaria<\/b> para la aplicaci\u00f3n de la nueva pol\u00edtica. Adem\u00e1s, Trump se reserva el derecho de modificar la orden en funci\u00f3n de nueva informaci\u00f3n, recomendaciones de altos funcionarios o cambios en las circunstancias, para garantizar la eficacia de la respuesta a la \u201cemergencia nacional\u201d.<\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/PHCDYMULIBIOL25DPGZVU6KNMM.jpg?auth=d6678ab9cbd63f7d439960d0bd609dfb9a4479316357ab169bee575c8d105d6f&amp;smart=true&amp;width=992&amp;height=661&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/PHCDYMULIBIOL25DPGZVU6KNMM.jpg?auth=d6678ab9cbd63f7d439960d0bd609dfb9a4479316357ab169bee575c8d105d6f&amp;smart=true&amp;width=768&amp;height=512&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/PHCDYMULIBIOL25DPGZVU6KNMM.jpg?auth=d6678ab9cbd63f7d439960d0bd609dfb9a4479316357ab169bee575c8d105d6f&amp;smart=true&amp;width=577&amp;height=385&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/PHCDYMULIBIOL25DPGZVU6KNMM.jpg?auth=d6678ab9cbd63f7d439960d0bd609dfb9a4479316357ab169bee575c8d105d6f&amp;smart=true&amp;width=420&amp;height=280&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/PHCDYMULIBIOL25DPGZVU6KNMM.jpg?auth=d6678ab9cbd63f7d439960d0bd609dfb9a4479316357ab169bee575c8d105d6f&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"Donald Trump y el ayatol\u00e1\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"1335\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/PHCDYMULIBIOL25DPGZVU6KNMM.jpg?auth=d6678ab9cbd63f7d439960d0bd609dfb9a4479316357ab169bee575c8d105d6f&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"2003\"\/><\/picture><figcaption class=\"article-figcaption-img\">Donald Trump y el ayatol\u00e1 Ali Khamenei (Oficina del l\u00edder supremo de Ir\u00e1n\/AP\/Archivo)<\/figcaption><\/div>\n<p class=\"paragraph\">La Casa Blanca dio a conocer esta orden ejecutiva el mismo d\u00eda en que concluyeron en Mascate, Om\u00e1n, las conversaciones indirectas entre Estados Unidos e Ir\u00e1n sobre el programa nuclear iran\u00ed.<\/p>\n<p class=\"paragraph\">Seg\u00fan el pa\u00eds mediador, las reuniones se centraron en \u201ccrear las condiciones apropiadas para el reinicio de las negociaciones diplom\u00e1ticas y t\u00e9cnicas\u201d. Ir\u00e1n describi\u00f3 un \u201cbuen ambiente\u201d y un \u201cbuen comienzo\u201d de las negociaciones, al se\u00f1alar un acuerdo \u201ccasi total\u201d para continuar los contactos.<\/p>\n<p class=\"paragraph\">En ese sentido, el presidente estadounidense asegur\u00f3 que Washington mantuvo \u201c<b>muy buenas conversaciones<\/b>\u201d en Om\u00e1n, tras los di\u00e1logos indirectos celebrados con el objetivo de evitar una escalada de tensiones.<\/p>\n<p class=\"paragraph\">\u201cMantuve muy buenas conversaciones sobre Ir\u00e1n, <b>parece que Ir\u00e1n quiere llegar a un acuerdo con muchas ganas<\/b>\u201d, declar\u00f3 Trump a periodistas a bordo del Air Force One, rumbo a su residencia de Mar-a-Lago, en Florida.<\/p>\n<p class=\"paragraph\">El mandatario adelant\u00f3 adem\u00e1s que las delegaciones se volver\u00e1n a reunir \u201ca principios de la pr\u00f3xima semana\u201d. \u201cTenemos que ver cu\u00e1l es ese acuerdo. Pero creo que Ir\u00e1n parece que tiene muchas ganas de llegar a un acuerdo, como deber\u00eda ser. <b>La \u00faltima vez quiz\u00e1 decidieron no hacerlo, pero creo que probablemente ahora piensan de manera diferente<\/b>\u201d, expres\u00f3 Trump, y agreg\u00f3: \u201cLas consecuencias son muy duras. As\u00ed que veremos qu\u00e9 pasa. Pero ha sido una conversaci\u00f3n muy buena\u201d.<\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/EGB7GG5MJVBYVPDIQI5BQTMIXQ.jpg?auth=50c2f053cc3645dbffa6b38e3c4acfa80dbaae178461932e34e1a9bb601adc67&amp;smart=true&amp;width=992&amp;height=660&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/EGB7GG5MJVBYVPDIQI5BQTMIXQ.jpg?auth=50c2f053cc3645dbffa6b38e3c4acfa80dbaae178461932e34e1a9bb601adc67&amp;smart=true&amp;width=768&amp;height=511&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/EGB7GG5MJVBYVPDIQI5BQTMIXQ.jpg?auth=50c2f053cc3645dbffa6b38e3c4acfa80dbaae178461932e34e1a9bb601adc67&amp;smart=true&amp;width=577&amp;height=384&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/EGB7GG5MJVBYVPDIQI5BQTMIXQ.jpg?auth=50c2f053cc3645dbffa6b38e3c4acfa80dbaae178461932e34e1a9bb601adc67&amp;smart=true&amp;width=420&amp;height=280&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/EGB7GG5MJVBYVPDIQI5BQTMIXQ.jpg?auth=50c2f053cc3645dbffa6b38e3c4acfa80dbaae178461932e34e1a9bb601adc67&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"El petr\u00f3leo escal\u00f3 a m\u00e1ximos\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"1278\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/EGB7GG5MJVBYVPDIQI5BQTMIXQ.jpg?auth=50c2f053cc3645dbffa6b38e3c4acfa80dbaae178461932e34e1a9bb601adc67&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"1920\"\/><\/picture><figcaption class=\"article-figcaption-img\">El petr\u00f3leo escal\u00f3 a m\u00e1ximos de cuatro meses, por encima de 70 d\u00f3lares, ante las tensiones con Ir\u00e1n (Europa Press)<\/figcaption><\/div>\n<p class=\"paragraph\">Tras el encuentro en Om\u00e1n, el ministro de Relaciones Exteriores de Ir\u00e1n,<b> Abaas Araqchi<\/b>, calific\u00f3 las conversaciones de \u201cmuy positivas\u201d. En declaraciones a la televisi\u00f3n estatal iran\u00ed, despu\u00e9s de negociar con el enviado especial estadounidense para Medio Oriente, <b>Steve Witkoff<\/b>, y el yerno de Trump, <b>Jared Kushner<\/b>, Araqchi afirm\u00f3: \u201cIntercambiamos nuestros puntos de vista\u201d. El canciller iran\u00ed consider\u00f3 que \u201ces un buen comienzo\u201d y se\u00f1al\u00f3 que ambas partes \u201cacordaron continuar las negociaciones, pero las modalidades y el calendario se decidir\u00e1n posteriormente\u201d. Tras la reuni\u00f3n, el funcionario parti\u00f3 hacia Doha, Qatar.<\/p>\n<p class=\"paragraph\">El <b>Ministerio de Asuntos Exteriores de Om\u00e1n<\/b> confirm\u00f3 a trav\u00e9s de X que actu\u00f3 como mediador en las conversaciones sobre el programa nuclear iran\u00ed. El canciller oman\u00ed, <b>Badr al-Busaidi<\/b>, mantuvo reuniones por separado con Araqchi, Witkoff y Kushner. Seg\u00fan la canciller\u00eda oman\u00ed, \u201clas consultas se centraron en preparar las circunstancias apropiadas para reanudar las negociaciones diplom\u00e1ticas y t\u00e9cnicas, asegurando la importancia de estas negociaciones, a la luz de la determinaci\u00f3n de las partes de asegurar su \u00e9xito en el logro de una seguridad y estabilidad sostenibles\u201d.<\/p>\n<p class=\"paragraph\">Por otra parte, la administraci\u00f3n de Trump anunci\u00f3 el viernes nuevas sanciones para frenar las exportaciones petroleras de Ir\u00e1n. Seg\u00fan inform\u00f3 el <b>Departamento de Estado<\/b>, las medidas afectan a <b>15 entidades, dos personas y 14 buques<\/b> de la llamada \u201c<b>flota fantasma<\/b>\u201d vinculados al comercio de petr\u00f3leo y productos petrol\u00edferos iran\u00edes.<\/p>\n<p class=\"paragraph\">El portavoz del Departamento de Estado, <b>Tommy Pigott<\/b>, afirm\u00f3 que el mandatario norteamericano est\u00e1 \u201ccomprometido a reducir las exportaciones il\u00edcitas de petr\u00f3leo y petroqu\u00edmicos del r\u00e9gimen iran\u00ed bajo la campa\u00f1a de m\u00e1xima presi\u00f3n de la administraci\u00f3n\u201d.<\/p>\n<\/div>\n<p><script defer=\"\">try{!function(f,b,e,v,n,t,s) {if(f.fbq)return;n=f.fbq=function(){n.callMethod? n.callMethod.apply(n,arguments):n.queue.push(arguments)}; if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0'; n.queue=[];t=b.createElement(e);t.async=!0; t.src=v;s=b.getElementsByTagName(e)[0]; s.parentNode.insertBefore(t,s)}(window, document,'script', ' fbq('init', '336383993555320'); fbq('track', 'PageView'); fbq('track', 'ViewContent');}catch(error){console.log(\"Error al inicializar facebookPixelRawCodeScript:\",error);}<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EEUU anunici\u00f3 nuevos aranceles a pa\u00edses que comercien con Ir\u00e1n (Europa Press) El presidente estadounidense, Donald Trump, anunci\u00f3 la imposici\u00f3n de un arancel adicional a los productos de pa\u00edses que mantengan v\u00ednculos comerciales con el r\u00e9gimen de Ir\u00e1n, argumentando que \u201clas acciones y pol\u00edticas del gobierno iran\u00ed constituyen una amenaza inusual y extraordinaria para la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":77941,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/77940"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=77940"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/77940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/77941"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=77940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=77940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=77940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}