{"id":72636,"date":"2026-01-18T23:32:07","date_gmt":"2026-01-19T02:32:07","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2026\/01\/18\/la-declaracion-de-paulo-dybala-sobre-su-futuro-que-ilusiona-a-los-hinchas-de-boca\/"},"modified":"2026-01-18T23:32:07","modified_gmt":"2026-01-19T02:32:07","slug":"la-declaracion-de-paulo-dybala-sobre-su-futuro-que-ilusiona-a-los-hinchas-de-boca","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2026\/01\/18\/la-declaracion-de-paulo-dybala-sobre-su-futuro-que-ilusiona-a-los-hinchas-de-boca\/","title":{"rendered":"La declaraci\u00f3n de Paulo Dybala sobre su futuro que ilusiona a los hinchas de Boca"},"content":{"rendered":"<p><\/p>\n<h2 class=\"article-subheadline text_align_left\">El Xeneize aspira a contar con la Joya, que vive un momento de incertidumbre en la Roma de Italia<\/h2>\n<p><\/p>\n<p class=\"paragraph\">El nombre de <b>Paulo Dybala<\/b> figura como el principal anhelo de la dirigencia de <b>Boca Juniors<\/b> para el plantel de 2026. La situaci\u00f3n contractual del delantero aumenta las esperanzas de concentrar el fichaje ante <b>la posibilidad de que el futbolista abandone Italia a mitad de a\u00f1o<\/b>, sumado a que ya hab\u00eda despertado inter\u00e9s en el club desde la llegada de <b>Leandro Paredes<\/b>.<\/p>\n<p><\/p>\n<p class=\"paragraph\">Seg\u00fan detall\u00f3 el periodista italiano <i><b>Nicol\u00f2 Schira<\/b><\/i>, <b>el v\u00ednculo entre el delantero y la Roma finalizar\u00e1 en junio<\/b> y las gestiones para renovar el acuerdo no han avanzado. La directiva del club italiano eval\u00faa alternativas y <b>estar\u00eda dispuesta a negociar la transferencia de Dybala durante este mercado de pases<\/b> por un monto cercano a los<b> 2 o 3 millones de d\u00f3lares<\/b>. En caso de no llegar a un acuerdo con alg\u00fan equipo, <b>el delantero quedar\u00eda en condici\u00f3n de libre<\/b> en el pr\u00f3ximo verano europeo, lo que aumentar\u00eda el inter\u00e9s de clubes que buscan fichajes destacados sin costo de transferencia.<\/p>\n<p><\/p>\n<p class=\"paragraph\">Esta condici\u00f3n <b>habilita al delantero a firmar un preacuerdo con cualquier club<\/b> y quedar con el pase libre para el pr\u00f3ximo mercado de pases, lo que facilita su posible llegada al f\u00fatbol argentino. Mientras tanto, <b>en Boca mantienen la expectativa sobre los pasos que dar\u00e1 el futbolista y la postura definitiva de la Roma<\/b>. <\/p>\n<p><\/p>\n<p class=\"paragraph\">Las conversaciones sobre una posible renovaci\u00f3n entre Paulo Dybala y la Roma llegaron a un punto cr\u00edtico debido a <b>las condiciones impuestas por la dirigencia <\/b>del club italiano. Aunque <b>en un principio exist\u00eda la intenci\u00f3n de extender el v\u00ednculo<\/b>, la propuesta presentada <b>incluy\u00f3 una reducci\u00f3n considerable en el salario del delantero<\/b>.<\/p>\n<p><\/p>\n<p class=\"paragraph\">La oferta de la Roma establec\u00eda que Dybala percibiera cerca de <b>3 millones y medio de d\u00f3lares anuales<\/b>, una cifra muy inferior a los aproximadamente <b>9 millones netos<\/b> que recibe en la actualidad. Este recorte salarial se transform\u00f3 en el principal obst\u00e1culo para avanzar en las negociaciones, seg\u00fan trascendi\u00f3 en medios italianos.<\/p>\n<p><\/p>\n<p class=\"paragraph\">A pesar de que todav\u00eda no existen gestiones formales entre ambas partes, <b>la conducci\u00f3n del club argentino analiza la situaci\u00f3n con atenci\u00f3n<\/b>, ante la necesidad de <b>sumar refuerzos de jerarqu\u00eda para afrontar una temporada exigente<\/b>. La <b>Copa Libertadores<\/b> aparece como un factor determinante en la posibilidad de convencer al delantero y concretar su llegada a mitad de a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Xeneize aspira a contar con la Joya, que vive un momento de incertidumbre en la Roma de Italia El nombre de Paulo Dybala figura como el principal anhelo de la dirigencia de Boca Juniors para el plantel de 2026. La situaci\u00f3n contractual del delantero aumenta las esperanzas de concentrar el fichaje ante la posibilidad [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":67761,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/72636"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=72636"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/72636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/67761"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=72636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=72636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=72636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}