{"id":55917,"date":"2025-10-31T17:59:04","date_gmt":"2025-10-31T20:59:04","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2025\/10\/31\/2046contexto-desafiante-norton-una-de-la-bodegas-mas-reconocidas-de-la-argentina-solicito-el-concurso-de-acreedores\/"},"modified":"2025-10-31T17:59:04","modified_gmt":"2025-10-31T20:59:04","slug":"2046contexto-desafiante-norton-una-de-la-bodegas-mas-reconocidas-de-la-argentina-solicito-el-concurso-de-acreedores","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2025\/10\/31\/2046contexto-desafiante-norton-una-de-la-bodegas-mas-reconocidas-de-la-argentina-solicito-el-concurso-de-acreedores\/","title":{"rendered":"20:46\u201cContexto desafiante\u201d: Norton, una de la bodegas m\u00e1s reconocidas de la Argentina, solicit\u00f3 el concurso de acreedores"},"content":{"rendered":"<p><\/p>\n<h2 class=\"article-subheadline text_align_left\">\u201cEsta decisi\u00f3n fue tomada para asegurar los puestos de trabajo y la continuidad de la operaci\u00f3n\u201d, dijo la empresa<\/h2>\n<p><\/p>\n<p class=\"paragraph\"><b>Bodega Norton <\/b>se present\u00f3 hoy en <b>Concurso Preventivo de Acreedores<\/b>. <\/p>\n<p><\/p>\n<p class=\"paragraph\">Norton, una de las bodegas l\u00edderes y de mayor trayectoria del pa\u00eds, fue fundada en 1895 en Luj\u00e1n de Cuyo, Mendoza. Seg\u00fan destaca la propia empresa, con m\u00e1s de 128 cosechas y tiene presencia en m\u00e1s de 72 pa\u00edses alrededor del mundo. <\/p>\n<p><\/p>\n<p class=\"paragraph\">\u201cDesde su misi\u00f3n, Norton crea una amplia gama de vinos, desde varietales hasta <i>blends<\/i> de alta gama y experiencias de alto valor percibido que impacten positivamente en consumidores, socios comerciales y colaboradores que valoran la trayectoria, prestigio y confiabilidad\u201d, detallaron. <\/p>\n<p><\/p>\n<p class=\"paragraph\"><i>Noticia en desarrollo<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEsta decisi\u00f3n fue tomada para asegurar los puestos de trabajo y la continuidad de la operaci\u00f3n\u201d, dijo la empresa Bodega Norton se present\u00f3 hoy en Concurso Preventivo de Acreedores. Norton, una de las bodegas l\u00edderes y de mayor trayectoria del pa\u00eds, fue fundada en 1895 en Luj\u00e1n de Cuyo, Mendoza. Seg\u00fan destaca la propia empresa, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":55918,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/55917"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=55917"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/55917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/55918"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=55917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=55917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=55917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}