{"id":55892,"date":"2025-10-31T15:29:04","date_gmt":"2025-10-31T18:29:04","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2025\/10\/31\/lluvia-de-elogios-al-inmenso-valentin-barco-en-francia-es-practicamente-el-mejor-jugador-del-torneo\/"},"modified":"2025-10-31T15:29:04","modified_gmt":"2025-10-31T18:29:04","slug":"lluvia-de-elogios-al-inmenso-valentin-barco-en-francia-es-practicamente-el-mejor-jugador-del-torneo","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2025\/10\/31\/lluvia-de-elogios-al-inmenso-valentin-barco-en-francia-es-practicamente-el-mejor-jugador-del-torneo\/","title":{"rendered":"Lluvia de elogios al \u201cinmenso\u201d Valent\u00edn Barco en Francia: \u201dEs pr\u00e1cticamente el mejor jugador del torneo&#8221;"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\"jwplayer-ctn\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/VideoObject\"><meta itemprop=\"contentUrl\" content=\"https:\/\/cdn.jwplayer.com\/videos\/ECTiJhtv-B3B0AgVE.mp4\"\/><meta itemprop=\"description\" content=\"El video que comparti\u00f3 Racing Estrasburgo de Valent\u00edn Barco\"\/><meta itemprop=\"duration\" content=\"P0Y0M0DT0H0M79S\"\/><meta itemprop=\"name\" content=\"El video que comparti\u00f3 Racing Estrasburgo de Valent\u00edn Barco\"\/><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/cdn.jwplayer.com\/v2\/media\/ECTiJhtv\/poster.jpg?width=720\"\/><meta itemprop=\"uploadDate\" content=\"2025-10-31T15:24:30.000Z\"\/><figcaption class=\"jwplayer-figcaption\">El video que comparti\u00f3 Racing Estrasburgo de Valent\u00edn Barco<\/figcaption><\/div>\n<p class=\"paragraph\"><b>Valent\u00edn Barco<\/b> se transform\u00f3 en una de las estrellas en ascenso del f\u00fatbol franc\u00e9s y el partido que jug\u00f3 en la goleada 3-0 sobre Auxerre \u2013que tambi\u00e9n tuvo un tanto del argentino <b>Joaqu\u00edn Panichelli<\/b>\u2013 lo puso en los reflectores de los medios locales.<\/p>\n<p class=\"paragraph\">El periodista Bernard Lions del reconocido diario franc\u00e9s <i>L\u2019Equipe<\/i> centr\u00f3 su an\u00e1lisis en el rendimiento del argentino. <b>\u201cChispa, creador de juego, goleador&#8230; Barco sigue subiendo con el Estrasburgo<\/b>\u201d, titul\u00f3 el art\u00edculo que retrat\u00f3 c\u00f3mo el lateral est\u00e1 alimentando la esperanza de clasificar a la Champions League de su equipo.<\/p>\n<p class=\"paragraph\">El cronista lo apod\u00f3 como el \u201cpetit lutin argentin\u201d (peque\u00f1o duende argentino) cuando repas\u00f3 su salida del campo de juego a los 62 minutos de la goleada 3-0 ante Auxerre que tuvo su primer tanto en Francia y una asistencia para la anotaci\u00f3n de Sebastian Nanasi. \u201cLevant\u00f3 r\u00e1pidamente la vista al o\u00edr los v\u00edtores de todo un <i>Meinau <\/i>enamorado. Incluso Liam Rosenior, su entrenador, le dedic\u00f3 un fuerte aplauso. Entonces, Barco esboz\u00f3 una sonrisa cort\u00e9s. En el fondo, pod\u00eda sentir la satisfacci\u00f3n del deber cumplido\u201d, describi\u00f3.<\/p>\n<p class=\"paragraph\">\u201cPara ello, solo necesit\u00f3 una hora. Durante ese tiempo, impulsado por la \u2018Garra Charr\u00faa\u2019, el esp\u00edritu guerrero de sus primos uruguayos, el combativo internacional <b>argentino volvi\u00f3 a imponerse como el jugador que m\u00e1s duelos disput\u00f3 y gan\u00f3<\/b> (seis de nueve), todos en el suelo, y que m\u00e1s balones recuper\u00f3 (6). Pero eso no es todo\u201d, lo elogi\u00f3, resaltando tambi\u00e9n la \u201ccontribuci\u00f3n ofensiva\u201d que \u201cresult\u00f3 decisiva\u201d en tres ocasiones.<\/p>\n<p class=\"paragraph\">Valent\u00edn suma <b>29 presentaciones con Estrasburgo<\/b>, pero en estas \u00faltimas actuaciones <b>\u201cha cambiado definitivamente de dimensi\u00f3n\u201d <\/b>asegur\u00f3 el periodista, ya que sum\u00f3 tres asistencias y su primer tanto en los recientes cuatro partidos, duplicando la influencia ofensiva que hab\u00eda tenido en sus primeros 20 juegos donde hab\u00eda sumado dos asistencias.<\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/M54VLKMDJFEXPMB3HX4SMLS2HE.JPG?auth=34343f89074f93ec38ccc73b22ab0b74cf1e502fca02be191614d5f5a1616b1c&amp;smart=true&amp;width=992&amp;height=701&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/M54VLKMDJFEXPMB3HX4SMLS2HE.JPG?auth=34343f89074f93ec38ccc73b22ab0b74cf1e502fca02be191614d5f5a1616b1c&amp;smart=true&amp;width=768&amp;height=543&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/M54VLKMDJFEXPMB3HX4SMLS2HE.JPG?auth=34343f89074f93ec38ccc73b22ab0b74cf1e502fca02be191614d5f5a1616b1c&amp;smart=true&amp;width=577&amp;height=408&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/M54VLKMDJFEXPMB3HX4SMLS2HE.JPG?auth=34343f89074f93ec38ccc73b22ab0b74cf1e502fca02be191614d5f5a1616b1c&amp;smart=true&amp;width=420&amp;height=297&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/M54VLKMDJFEXPMB3HX4SMLS2HE.JPG?auth=34343f89074f93ec38ccc73b22ab0b74cf1e502fca02be191614d5f5a1616b1c&amp;smart=true&amp;width=350&amp;height=247&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"Barco anot\u00f3 su primer tanto\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"2167\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/M54VLKMDJFEXPMB3HX4SMLS2HE.JPG?auth=34343f89074f93ec38ccc73b22ab0b74cf1e502fca02be191614d5f5a1616b1c&amp;smart=true&amp;width=350&amp;height=247&amp;quality=85\" width=\"3066\"\/><\/picture><figcaption class=\"article-figcaption-img\">Barco anot\u00f3 su primer tanto en Racing Estrasburgo ante Auxerre (Foto: Reuters\/Sarah Meyssonnier)<\/figcaption><\/div>\n<p class=\"paragraph\">El medio <i>Derni\u00e8res Nouvelles d\u2019Alsace<\/i> (<i>DNA<\/i>) enfocado en las noticias de Estrasburgo asegur\u00f3 que <b>\u201cValent\u00edn Barco es inmenso\u201d<\/b> en el art\u00edculo que firm\u00f3 el cronista Simon Giovannini con las calificaciones del partido: \u201c<b>Ya no nos sorprende porque nunca defrauda, pero Valent\u00edn Barco volvi\u00f3 a dar una lecci\u00f3n magistral<\/b> contra el Auxerre en el estadio de la Meinau. Asistente y goleador por primera vez en la Ligue 1, el <b>peque\u00f1o centrocampista argentino estuvo inmenso<\/b>\u201d.<\/p>\n<p class=\"paragraph\">El sitio oficial del club realiz\u00f3 una votaci\u00f3n entre los aficionados, quienes mencionaron al futbolista de 21 a\u00f1os como el m\u00e1s destacado del triunfo sobre Auxerre con el 68% de los votos totales. <\/p>\n<p class=\"paragraph\">\u201c<b>\u00a1Maestro! Valent\u00edn volvi\u00f3 a brillar contra Auxerre<\/b>. En el centro del campo, distribuyendo y recuperando balones, contribuy\u00f3 enormemente a que el equipo lograra una nueva victoria. El <i>Colo<\/i> realiz\u00f3 diecis\u00e9is pases hacia delante (el segundo mejor del partido), gan\u00f3 cinco duelos y recuper\u00f3 seis balones (el segundo mejor del partido). Y, como guinda del pastel, marc\u00f3 el tercer y \u00faltimo gol del partido, el primero con el Racing. Ha participado en cuatro goles en sus \u00faltimos cuatro partidos con el Estrasburgo (1 gol y 3 asistencias). Se trata de la tercera distinci\u00f3n de nuestro argentino&#8221;, argumentaron tras la decisi\u00f3n de los fan\u00e1ticos.<\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/YVOCG2WFOJFKFAVFVEG2NPGARQ.JPG?auth=9b556eed30591ad9351b30f98b0eac384c948ef5cf1c4a62692a31657015cc46&amp;smart=true&amp;width=992&amp;height=686&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/YVOCG2WFOJFKFAVFVEG2NPGARQ.JPG?auth=9b556eed30591ad9351b30f98b0eac384c948ef5cf1c4a62692a31657015cc46&amp;smart=true&amp;width=768&amp;height=531&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/YVOCG2WFOJFKFAVFVEG2NPGARQ.JPG?auth=9b556eed30591ad9351b30f98b0eac384c948ef5cf1c4a62692a31657015cc46&amp;smart=true&amp;width=577&amp;height=399&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/YVOCG2WFOJFKFAVFVEG2NPGARQ.JPG?auth=9b556eed30591ad9351b30f98b0eac384c948ef5cf1c4a62692a31657015cc46&amp;smart=true&amp;width=420&amp;height=290&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/YVOCG2WFOJFKFAVFVEG2NPGARQ.JPG?auth=9b556eed30591ad9351b30f98b0eac384c948ef5cf1c4a62692a31657015cc46&amp;smart=true&amp;width=350&amp;height=242&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"Los fan\u00e1ticos del club lo\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"3097\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/YVOCG2WFOJFKFAVFVEG2NPGARQ.JPG?auth=9b556eed30591ad9351b30f98b0eac384c948ef5cf1c4a62692a31657015cc46&amp;smart=true&amp;width=350&amp;height=242&amp;quality=85\" width=\"4479\"\/><\/picture><figcaption class=\"article-figcaption-img\">Los fan\u00e1ticos del club lo eligieron como el mejor jugador del \u00faltimo partido (Foto: Reuters\/Gonzalo Fuentes)<\/figcaption><\/div>\n<p class=\"paragraph\">Los elogios al argentino siguen creciendo en la liga francesa a punto tal que <i>L\u2019Equipe<\/i> plante\u00f3 en uno de sus env\u00edos televisivos la siguiente pregunta para el debate de sus periodistas: \u201cLigue 1: \u00bfEs Valent\u00edn Barco actualmente el mejor jugador de la liga?\u201c. Este mismo debate lo abri\u00f3 uno de los cronistas de este medio, Bernard Lions, cuando asegur\u00f3 que Barco es <b>\u201dpr\u00e1cticamente el mejor jugador del campeonato&#8221;<\/b>.<\/p>\n<p class=\"paragraph\">D\u00edas atr\u00e1s, el peri\u00f3dico <i>20minutes <\/i>hab\u00eda analizado el rendimiento del Racing de Estrasburgo, calific\u00e1ndolo como la sorpresa del certamen y <b>definiendo a Barco como el \u201crey del Imperio del centro\u201d<\/b><i>.<\/i><\/p>\n<p class=\"paragraph\">La agenda de presentaciones tendr\u00e1 al elenco franc\u00e9s visitando al <b>Rennes <\/b>el pr\u00f3ximo domingo desde las 11 de la ma\u00f1ana de Argentina por la 11\u00aa fecha de la <b>Ligue 1<\/b>. Los dirigidos por el ingl\u00e9s Liam Rosenior figuran cuartos en el certamen con 19 puntos, pero apenas dos unidades por detr\u00e1s del l\u00edder PSG que tiene 21. Luego, el jueves 6, visitar\u00e1n al <b>BK H\u00e4cken de Suecia<\/b> por la 3\u00aa jornada de la <b>Conference League<\/b> que los tiene con cuatro puntos tras la victoria sobre Bratislava 2-1 y el posterior empate ante Jagiellonia Bialystok.<\/p>\n<p class=\"paragraph\">Valent\u00edn se fue del f\u00fatbol argentino en medio de una pol\u00e9mica con <b>Boca Juniors<\/b> cuando decidi\u00f3 ejecutar la cl\u00e1usula y dej\u00f3 m\u00e1s de 9 millones de d\u00f3lares en las arcas del club para militar en el <b>Brighton &amp; Hove Albion de Inglaterra<\/b>. Sin embargo, no logr\u00f3 asentarse en la Premier League y emigr\u00f3 en enero de este a\u00f1o al club franc\u00e9s, que tras un semestre decidi\u00f3 poner sobre la mesa <b>unos 10 millones de euros<\/b> para conseguir su fichaje definitivo.<\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/QT2FUR6TYRE4NEHDOV6PL4BNKI.JPG?auth=b692ee48271434c1a75d27f7e202cef66cd647e6ed5e5e79211d78c0facc8096&amp;smart=true&amp;width=992&amp;height=735&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/QT2FUR6TYRE4NEHDOV6PL4BNKI.JPG?auth=b692ee48271434c1a75d27f7e202cef66cd647e6ed5e5e79211d78c0facc8096&amp;smart=true&amp;width=768&amp;height=569&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/QT2FUR6TYRE4NEHDOV6PL4BNKI.JPG?auth=b692ee48271434c1a75d27f7e202cef66cd647e6ed5e5e79211d78c0facc8096&amp;smart=true&amp;width=577&amp;height=427&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/QT2FUR6TYRE4NEHDOV6PL4BNKI.JPG?auth=b692ee48271434c1a75d27f7e202cef66cd647e6ed5e5e79211d78c0facc8096&amp;smart=true&amp;width=420&amp;height=311&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/QT2FUR6TYRE4NEHDOV6PL4BNKI.JPG?auth=b692ee48271434c1a75d27f7e202cef66cd647e6ed5e5e79211d78c0facc8096&amp;smart=true&amp;width=350&amp;height=259&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"Barco con su entrenador Liam\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"1940\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/QT2FUR6TYRE4NEHDOV6PL4BNKI.JPG?auth=b692ee48271434c1a75d27f7e202cef66cd647e6ed5e5e79211d78c0facc8096&amp;smart=true&amp;width=350&amp;height=259&amp;quality=85\" width=\"2619\"\/><\/picture><figcaption class=\"article-figcaption-img\">Barco con su entrenador Liam Rosenior (Foto: Reuters\/Christian Hartmann)<\/figcaption><\/div>\n<\/div>\n<p><script defer=\"\">try{!function(f,b,e,v,n,t,s) {if(f.fbq)return;n=f.fbq=function(){n.callMethod? n.callMethod.apply(n,arguments):n.queue.push(arguments)}; if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0'; n.queue=[];t=b.createElement(e);t.async=!0; t.src=v;s=b.getElementsByTagName(e)[0]; s.parentNode.insertBefore(t,s)}(window, document,'script', ' fbq('init', '336383993555320'); fbq('track', 'PageView'); fbq('track', 'ViewContent');}catch(error){console.log(\"Error al inicializar facebookPixelRawCodeScript:\",error);}<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El video que comparti\u00f3 Racing Estrasburgo de Valent\u00edn Barco Valent\u00edn Barco se transform\u00f3 en una de las estrellas en ascenso del f\u00fatbol franc\u00e9s y el partido que jug\u00f3 en la goleada 3-0 sobre Auxerre \u2013que tambi\u00e9n tuvo un tanto del argentino Joaqu\u00edn Panichelli\u2013 lo puso en los reflectores de los medios locales. El periodista Bernard [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":55893,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/55892"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=55892"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/55892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/55893"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=55892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=55892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=55892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}