{"id":55887,"date":"2025-10-31T14:47:03","date_gmt":"2025-10-31T17:47:03","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2025\/10\/31\/el-inusual-gesto-de-jose-mourinho-con-nicolas-otamendi-en-pleno-discurso-sobre-el-argentino-merece-que-hable-en-su-idioma\/"},"modified":"2025-10-31T14:47:03","modified_gmt":"2025-10-31T17:47:03","slug":"el-inusual-gesto-de-jose-mourinho-con-nicolas-otamendi-en-pleno-discurso-sobre-el-argentino-merece-que-hable-en-su-idioma","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2025\/10\/31\/el-inusual-gesto-de-jose-mourinho-con-nicolas-otamendi-en-pleno-discurso-sobre-el-argentino-merece-que-hable-en-su-idioma\/","title":{"rendered":"El inusual gesto de Jos\u00e9 Mourinho con Nicol\u00e1s Otamendi en pleno discurso sobre el argentino: \u201cMerece que hable en su idioma\u201d"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\"jwplayer-ctn\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/VideoObject\"><meta itemprop=\"contentUrl\" content=\"https:\/\/cdn.jwplayer.com\/videos\/lX7eABvr-B3B0AgVE.mp4\"\/><meta itemprop=\"description\" content=\"El elogio de Mourinho a Otamendi por sus 250 partidos en Benfica\"\/><meta itemprop=\"duration\" content=\"P0Y0M0DT0H0M120S\"\/><meta itemprop=\"name\" content=\"El elogio de Mourinho a Otamendi por sus 250 partidos en Benfica\"\/><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/cdn.jwplayer.com\/v2\/media\/lX7eABvr\/poster.jpg?width=720\"\/><meta itemprop=\"uploadDate\" content=\"2025-10-31T16:21:57.000Z\"\/><figcaption class=\"jwplayer-figcaption\">El elogio de Mourinho a Otamendi por sus 250 partidos en Benfica<\/figcaption><\/div>\n<p class=\"paragraph\"><b>Nicol\u00e1s Otamendi <\/b>contin\u00faa cumpliendo hitos a nivel personal con su club. Esta vez fue homenajeado en el vestuario del <b>Benfica <\/b>luego de haber llegado a los <b>250 partidos<\/b> con la camiseta del conjunto portugu\u00e9s. El capit\u00e1n del equipo no solamente fue vitoreado por sus compa\u00f1eros tras recibir una camiseta con ese dorsal por parte del m\u00edtico Rui Costa, presidente de los lisboetas, sino que adem\u00e1s recibi\u00f3 un enorme elogio de <b>Jos\u00e9 Mourinho<\/b>, su entrenador.<\/p>\n<p class=\"paragraph\">Luego de que <i>Ota <\/i>tomara la palabra y agradeciera a los suyos por el obsequio, <i>Mou <\/i>habl\u00f3 frente a todos y tuvo el gran gesto de hacerlo en espa\u00f1ol en honor al argentino: <b>\u201c\u00c9l merece que hable en su idioma. Mi mensaje no es para ti (se\u00f1al\u00f3 a Otamendi), es para los otros. El otro d\u00eda, al minuto 95, hubo un contraataque contra nuestro equipo y \u00e9l hizo un sprint de 75 metros cuando el resultado estaba 2-0 a favor. El mensaje no es para \u00e9l, es para ustedes\u201d<\/b>. Las frases de Mourinho, en referencia al \u00faltimo triunfo ante Tondela por Copa de Portugal, fueron concluidas con un aplauso general.<\/p>\n<p class=\"paragraph\">Esta no es la primera vez que Mourinho elogia p\u00fablicamente al defensor de la selecci\u00f3n argentina. Hace algunos d\u00edas, al ser consultado por el futuro del campe\u00f3n del mundo (su contrato en Portugal vence en junio de 2026), <b>el DT respondi\u00f3<\/b>: \u201cCreo que con los futbolistas una cosa es la edad real y otra cosa es lo que vemos en el campo y, en mi caso, como entrenador, no es solo lo que veo en el campo durante el partido, sino tambi\u00e9n lo que veo durante los entrenamientos. Hay j\u00f3venes de 20 a\u00f1os que son jugadores viejos y hay viejos (espero que no se ofendan porque yo soy m\u00e1s viejo que ellos), pero hay viejos de 38 y 40 a\u00f1os que son j\u00f3venes futbolistas. <b>Nico (Otamendi) es joven<\/b>\u201d. El zaguero central surgido en V\u00e9lez cumplir\u00e1 38 a\u00f1os en febrero pr\u00f3ximo.<\/p>\n<div class=\"visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/MYEFNT2VX5GE7DXR2FT4XA2WGU.jpg?auth=788df5d12b0493997b91ec8c765d9b011c0c4bfd0c21968ca47ada57e51582a1&amp;smart=true&amp;width=992&amp;height=1239&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/MYEFNT2VX5GE7DXR2FT4XA2WGU.jpg?auth=788df5d12b0493997b91ec8c765d9b011c0c4bfd0c21968ca47ada57e51582a1&amp;smart=true&amp;width=768&amp;height=960&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/MYEFNT2VX5GE7DXR2FT4XA2WGU.jpg?auth=788df5d12b0493997b91ec8c765d9b011c0c4bfd0c21968ca47ada57e51582a1&amp;smart=true&amp;width=577&amp;height=721&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/MYEFNT2VX5GE7DXR2FT4XA2WGU.jpg?auth=788df5d12b0493997b91ec8c765d9b011c0c4bfd0c21968ca47ada57e51582a1&amp;smart=true&amp;width=420&amp;height=525&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/MYEFNT2VX5GE7DXR2FT4XA2WGU.jpg?auth=788df5d12b0493997b91ec8c765d9b011c0c4bfd0c21968ca47ada57e51582a1&amp;smart=true&amp;width=350&amp;height=437&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"Otamendi y Mourinho son confidente\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"2399\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/MYEFNT2VX5GE7DXR2FT4XA2WGU.jpg?auth=788df5d12b0493997b91ec8c765d9b011c0c4bfd0c21968ca47ada57e51582a1&amp;smart=true&amp;width=350&amp;height=437&amp;quality=85\" width=\"1920\"\/><\/picture><figcaption class=\"article-figcaption-img\">Otamendi y Mourinho son confidente son Benfica (@slbenfica)<\/figcaption><\/div>\n<p class=\"paragraph\"><i>Mou <\/i>tambi\u00e9n relat\u00f3 una reciente conversaci\u00f3n que mantuvo con su capit\u00e1n, en la que qued\u00f3 reflejada la sinton\u00eda y el compromiso del defensor con el equipo: \u201cPara que comprendas un poco mi relaci\u00f3n con Otamendi y el nivel de nuestra comunicaci\u00f3n, le pregunt\u00e9 muy objetivamente: \u2018Tenemos Guimar\u00e3es y tenemos, eh, y tenemos Leverkusen&#8230; \u00bfQu\u00e9 hacemos ma\u00f1ana?\u2019. \u00c9l dijo: \u2018Tenemos Guimar\u00e3es, tenemos Leverkusen y tenemos Tondela\u2019. Listo, juega. <b>Es un jugador muy importante para nosotros<\/b>\u201d.<\/p>\n<p class=\"paragraph\">En cuanto a las especulaciones sobre el futuro del defensor, especialmente ante los rumores que lo vinculan como posible refuerzo de <b>River Plate<\/b> \u2014club del que es hincha\u2014, Mourinho fue tajante al delimitar su rol en las decisiones contractuales: \u201cPara las cuestiones contractuales y cuestiones de futuro tenemos gente en un nivel muy superior al m\u00edo para decidir. Las preguntas que me hagan, aqu\u00ed estoy para responderlas\u201d.<\/p>\n<p class=\"paragraph\">La admiraci\u00f3n de Mourinho por Otamendi no es nueva. En una conferencia de prensa anterior, previa al partido contra Rio Ave por la Primeira Liga, el entrenador volvi\u00f3 a elogiar el liderazgo del argentino: \u201cHay clubes donde el brazalete pertenece a quien ha jugado m\u00e1s partidos o alguien de la misma nacionalidad que el club. En este caso, el brazalete est\u00e1 en el brazo de alguien que es realmente el capit\u00e1n, que se considera capit\u00e1n y tiene el peso de un capit\u00e1n\u201d.<\/p>\n<p class=\"paragraph\">A lo largo de su carrera en el Benfica, <b>Otamendi<\/b> disput\u00f3 <b>250 partidos<\/b>, en los que convirti\u00f3 <b>16 goles<\/b> y brind\u00f3 <b>11 asistencias<\/b>, adem\u00e1s de conquistar <b>4 t\u00edtulos<\/b> con el club portugu\u00e9s. Su trayectoria profesional comenz\u00f3 en <b>V\u00e9lez<\/b>, donde jug\u00f3 cincuenta y cinco encuentros, y continu\u00f3 en el <b>Porto<\/b> (125 partidos), <b>Atl\u00e9tico Mineiro<\/b> (19), <b>Valencia<\/b> (38) y <b>Manchester City<\/b> (210). Con la <b>selecci\u00f3n argentina<\/b>, el defensor suma <b>129 partidos<\/b> y <b>siete goles<\/b>, habiendo obtenido el Mundial 2022, dos Copas Am\u00e9rica y la Final\u00edssima.<\/p>\n<\/div>\n<p><script defer=\"\">try{!function(f,b,e,v,n,t,s) {if(f.fbq)return;n=f.fbq=function(){n.callMethod? n.callMethod.apply(n,arguments):n.queue.push(arguments)}; if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0'; n.queue=[];t=b.createElement(e);t.async=!0; t.src=v;s=b.getElementsByTagName(e)[0]; s.parentNode.insertBefore(t,s)}(window, document,'script', ' fbq('init', '336383993555320'); fbq('track', 'PageView'); fbq('track', 'ViewContent');}catch(error){console.log(\"Error al inicializar facebookPixelRawCodeScript:\",error);}<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El elogio de Mourinho a Otamendi por sus 250 partidos en Benfica Nicol\u00e1s Otamendi contin\u00faa cumpliendo hitos a nivel personal con su club. Esta vez fue homenajeado en el vestuario del Benfica luego de haber llegado a los 250 partidos con la camiseta del conjunto portugu\u00e9s. El capit\u00e1n del equipo no solamente fue vitoreado por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":55888,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/55887"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=55887"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/55887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/55888"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=55887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=55887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=55887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}