{"id":55858,"date":"2025-10-31T11:45:04","date_gmt":"2025-10-31T14:45:04","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2025\/10\/31\/caso-cecilia-strzyzowski-que-declaro-el-abogado-de-emerenciano-sena-detenido-en-el-juicio\/"},"modified":"2025-10-31T11:45:04","modified_gmt":"2025-10-31T14:45:04","slug":"caso-cecilia-strzyzowski-que-declaro-el-abogado-de-emerenciano-sena-detenido-en-el-juicio","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2025\/10\/31\/caso-cecilia-strzyzowski-que-declaro-el-abogado-de-emerenciano-sena-detenido-en-el-juicio\/","title":{"rendered":"Caso Cecilia Strzyzowski: qu\u00e9 declar\u00f3 el abogado de Emerenciano Sena detenido en el juicio"},"content":{"rendered":"<p><\/p>\n<h2 class=\"article-subheadline text_align_left\">Nicol\u00e1s Boniardi Cabra est\u00e1 acusado de filmar a los candidatos del tribunal popular que juzgar\u00e1n el femicidio. Fue indagado este viernes. Seguir\u00e1 preso<\/h2>\n<p><\/p>\n<p class=\"paragraph\"><i>Resistencia, Chaco (enviada especial)<\/i>.<i> <\/i><i><b>Nicol\u00e1s Boniardi Cabra<\/b><\/i>, colaborador del abogado de <b>Emerenciano Sena<\/b>, fue indagado este viernes por la Justicia tras haber sido detenido en la segunda audiencia de selecci\u00f3n del jurado que juzgar\u00e1 a los imputados en el juicio por el femicidio de <i><b>Cecilia Strzyzowski<\/b><\/i>.<\/p>\n<p><\/p>\n<p class=\"paragraph\">La defensa podr\u00e1 dar la contrase\u00f1a del tel\u00e9fono en las pr\u00f3ximas horas. Caso contrario, el juez de garant\u00edas N\u00b01, Javier Roy, pedir\u00e1 la apertura del celular marca Iphone.<\/p>\n<p><\/p>\n<p class=\"paragraph\">El letrado, por ahora, continuar\u00e1 preso, alojado en la celda de la Comisar\u00eda 4\u00aa donde est\u00e1 desde el mi\u00e9rcoles.<\/p>\n<p><\/p>\n<p class=\"paragraph\">Por lo pronto, los delitos que enfrenta tienen una pena en expectativa que<b> no le impide transitar el proceso en libertad.<\/b><\/p>\n<p><\/p>\n<p class=\"paragraph\">Seg\u00fan supo este medio, Boniardi es conocido por distintos episodios que no le juegan a favor y, seg\u00fan confi\u00f3 otra fuente consultada por este medio, <b>no inspira demasiada confianza.<\/b><\/p>\n<p><\/p>\n<p class=\"paragraph\">Quiz\u00e1 por eso no llam\u00f3 la atenci\u00f3n cuando, durante la segunda audiencia de selecci\u00f3n de jurados, fue descubierto por<b> <\/b>los agentes de seguridad <b> <\/b>mientras<b> manipulaba el tel\u00e9fono <\/b>a metros del jurado.<b> <\/b>Eso s\u00ed, la jueza Dolly Fern\u00e1ndez decidi\u00f3 \u201ctomar los reparos\u201d necesarios. Minutos despu\u00e9s, la magistrada orden\u00f3 que fuera retirado de la sala, que se le secuestrara el tel\u00e9fono y que quedara a disposici\u00f3n de la fiscal\u00eda de turno.<b> Luego, qued\u00f3 preso.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicol\u00e1s Boniardi Cabra est\u00e1 acusado de filmar a los candidatos del tribunal popular que juzgar\u00e1n el femicidio. Fue indagado este viernes. Seguir\u00e1 preso Resistencia, Chaco (enviada especial). Nicol\u00e1s Boniardi Cabra, colaborador del abogado de Emerenciano Sena, fue indagado este viernes por la Justicia tras haber sido detenido en la segunda audiencia de selecci\u00f3n del jurado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":55859,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/55858"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=55858"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/55858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/55859"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=55858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=55858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=55858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}