{"id":27378,"date":"2024-11-29T19:10:03","date_gmt":"2024-11-29T22:10:03","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2024\/11\/29\/avanza-la-ley-que-permitira-la-eutanasia-en-el-reino-unido-fue-aprobada-por-la-camara-de-los-comunes\/"},"modified":"2024-11-29T19:10:03","modified_gmt":"2024-11-29T22:10:03","slug":"avanza-la-ley-que-permitira-la-eutanasia-en-el-reino-unido-fue-aprobada-por-la-camara-de-los-comunes","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2024\/11\/29\/avanza-la-ley-que-permitira-la-eutanasia-en-el-reino-unido-fue-aprobada-por-la-camara-de-los-comunes\/","title":{"rendered":"Avanza la ley que permitir\u00e1 la eutanasia en el Reino Unido: fue aprobada por la C\u00e1mara de los Comunes"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\" visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/36RQTXX4CBJNLONWBG6D3HFNNY.jpg?auth=8ae548be5ec5a758be02ed2f11f5cbbda50457f60da4fd239713c0a43f9b5cbb&amp;smart=true&amp;width=992&amp;height=558&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/36RQTXX4CBJNLONWBG6D3HFNNY.jpg?auth=8ae548be5ec5a758be02ed2f11f5cbbda50457f60da4fd239713c0a43f9b5cbb&amp;smart=true&amp;width=768&amp;height=432&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/36RQTXX4CBJNLONWBG6D3HFNNY.jpg?auth=8ae548be5ec5a758be02ed2f11f5cbbda50457f60da4fd239713c0a43f9b5cbb&amp;smart=true&amp;width=577&amp;height=325&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/36RQTXX4CBJNLONWBG6D3HFNNY.jpg?auth=8ae548be5ec5a758be02ed2f11f5cbbda50457f60da4fd239713c0a43f9b5cbb&amp;smart=true&amp;width=420&amp;height=236&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/36RQTXX4CBJNLONWBG6D3HFNNY.jpg?auth=8ae548be5ec5a758be02ed2f11f5cbbda50457f60da4fd239713c0a43f9b5cbb&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"La C\u00e1mara de los Comunes, en Londres (C\u00e1mara de los Comunes\/Parlamento del RU v\u00eda AP\/Archivo)\" class=\"global-image\" decoding=\"async\" fetchpriority=\"high\" height=\"2240\" loading=\"eager\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/36RQTXX4CBJNLONWBG6D3HFNNY.jpg?auth=8ae548be5ec5a758be02ed2f11f5cbbda50457f60da4fd239713c0a43f9b5cbb&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" width=\"4000\"\/><\/picture><figcaption class=\"article-figcaption-img\">La C\u00e1mara de los Comunes, en Londres (C\u00e1mara de los Comunes\/Parlamento del RU v\u00eda AP\/Archivo)<\/figcaption><\/div>\n<p class=\"paragraph\">La <b>C\u00e1mara de los Comunes brit\u00e1nica<\/b> (baja) aprob\u00f3 este viernes, por <b>330 votos a favor frente a 275 en contra<\/b>, la proposici\u00f3n de ley planteada por la diputada laborista <b>Kim Leadbeater<\/b> para<b> legalizar el suicidio asistido en Inglaterra y Gales<\/b>.<\/p>\n<p class=\"paragraph\">La diferencia de 55 votos <b>permitir\u00e1 que este texto prosiga su tr\u00e1mite parlamentario<\/b>, con la presentaci\u00f3n de enmiendas y escrutinio en la C\u00e1mara de los Lores (alta), previo a <b>un voto final que a\u00fan tardar\u00eda meses<\/b>.<\/p>\n<p class=\"paragraph\">Los diputados expresaron sus opiniones y debatieron los diferentes puntos de vista desde las 9:30 GMT hasta casi las 14:30 GMT, cuando se conoci\u00f3 el resultado de una votaci\u00f3n en la que <b>los partidos dieron a los parlamentarios libertad de sufragio<\/b>, al considerar que se trata de un <b>asunto de conciencia<\/b>.<\/p>\n<p class=\"paragraph\">En el caso del primer ministro brit\u00e1nico, <b>Keir Starmer<\/b>, que hab\u00eda mantenido una posici\u00f3n neutra hasta el momento, el recuento de votos mostr\u00f3 que<b> se posicion\u00f3 a favor de la proposici\u00f3n de ley<\/b>.<\/p>\n<p class=\"paragraph\">La denominada \u201cProposici\u00f3n de Ley de fin de vida para adultos con enfermedades terminales\u201d, cuya iniciativa legislativa corresponde a Leadbeater a t\u00edtulo personal, legalizar\u00eda en Inglaterra y Gales, en caso de que se produzca su aprobaci\u00f3n definitiva, que <b>los mayores de 18 a\u00f1os que padecen una enfermedad terminal puedan recibir asistencia para morir<\/b>.<\/p>\n<div class=\" visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/45PCO3IYUXIQ7MUEIHEJB4TYR4.jpg?auth=297b6ca0d83a2211161968563f393e9120421c662b28b4c1f0af9323f110c119&amp;smart=true&amp;width=992&amp;height=661&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/45PCO3IYUXIQ7MUEIHEJB4TYR4.jpg?auth=297b6ca0d83a2211161968563f393e9120421c662b28b4c1f0af9323f110c119&amp;smart=true&amp;width=768&amp;height=512&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/45PCO3IYUXIQ7MUEIHEJB4TYR4.jpg?auth=297b6ca0d83a2211161968563f393e9120421c662b28b4c1f0af9323f110c119&amp;smart=true&amp;width=577&amp;height=385&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/45PCO3IYUXIQ7MUEIHEJB4TYR4.jpg?auth=297b6ca0d83a2211161968563f393e9120421c662b28b4c1f0af9323f110c119&amp;smart=true&amp;width=420&amp;height=280&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/45PCO3IYUXIQ7MUEIHEJB4TYR4.jpg?auth=297b6ca0d83a2211161968563f393e9120421c662b28b4c1f0af9323f110c119&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"Personas reaccionan durante una manifestaci\u00f3n en apoyo de la muerte asistida fuera del parlamento brit\u00e1nico, en Londres (REUTERS\/Mina Kim)\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"3440\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/45PCO3IYUXIQ7MUEIHEJB4TYR4.jpg?auth=297b6ca0d83a2211161968563f393e9120421c662b28b4c1f0af9323f110c119&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"5130\"\/><\/picture><figcaption class=\"article-figcaption-img\">Personas reaccionan durante una manifestaci\u00f3n en apoyo de la muerte asistida fuera del parlamento brit\u00e1nico, en Londres (REUTERS\/Mina Kim)<\/figcaption><\/div>\n<p class=\"paragraph\">A diferencia de propuestas pasadas, que hab\u00edan resultado fallidas, la iniciativa de Leadbeater impone <b>m\u00e1s requisitos a los interesados<\/b> y convierte en <b>delito<\/b>, con <b>penas de hasta 14 a\u00f1os por presionar, coartar o enga\u00f1ar a alguien para que se quite la vida o declare que quiere acabar con ella<\/b>.<\/p>\n<p class=\"paragraph\"><b>Los interesados deben ser residentes de Inglaterra o Gales<\/b> y <b>llevar al menos 12 meses registrados con un m\u00e9dico de cabecera<\/b>, adem\u00e1s de tener una expectativa de vida de <b>menos de seis meses<\/b> y <b>estar en capacidad de tomar la decisi\u00f3n<\/b> y expresar un deseo \u201c<b>claro, firme, informado y libre de coerci\u00f3n o presi\u00f3n<\/b>\u201d.<\/p>\n<div class=\" visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/NNJL7LD7MS6YQM3L6EDLBE6MNI.jpg?auth=4db9c9add483af8e96425759610a35b4d1baf2e11202bfa63182820d5097286a&amp;smart=true&amp;width=992&amp;height=661&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/NNJL7LD7MS6YQM3L6EDLBE6MNI.jpg?auth=4db9c9add483af8e96425759610a35b4d1baf2e11202bfa63182820d5097286a&amp;smart=true&amp;width=768&amp;height=512&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/NNJL7LD7MS6YQM3L6EDLBE6MNI.jpg?auth=4db9c9add483af8e96425759610a35b4d1baf2e11202bfa63182820d5097286a&amp;smart=true&amp;width=577&amp;height=385&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/NNJL7LD7MS6YQM3L6EDLBE6MNI.jpg?auth=4db9c9add483af8e96425759610a35b4d1baf2e11202bfa63182820d5097286a&amp;smart=true&amp;width=420&amp;height=280&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/NNJL7LD7MS6YQM3L6EDLBE6MNI.jpg?auth=4db9c9add483af8e96425759610a35b4d1baf2e11202bfa63182820d5097286a&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"Manifestantes sostienen carteles frente al Parlamento mientras los legisladores brit\u00e1nicos debaten la ley de muerte asistida, en Londres (REUTERS\/Mina Kim)\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"3933\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/NNJL7LD7MS6YQM3L6EDLBE6MNI.jpg?auth=4db9c9add483af8e96425759610a35b4d1baf2e11202bfa63182820d5097286a&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"5900\"\/><\/picture><figcaption class=\"article-figcaption-img\">Manifestantes sostienen carteles frente al Parlamento mientras los legisladores brit\u00e1nicos debaten la ley de muerte asistida, en Londres (REUTERS\/Mina Kim)<\/figcaption><\/div>\n<p class=\"paragraph\">Los afectados tendr\u00e1n que hacer <b>dos declaraciones separadas, con testigos y firmadas<\/b>, sobre su deseo de morir, y deber\u00e1n someterse a la evaluaci\u00f3n de dos m\u00e9dicos y obtener una orden judicial.<\/p>\n<p class=\"paragraph\">El texto aprobado dispone que, aunque un m\u00e9dico podr\u00eda preparar el compuesto letal, <b>debe ser la persona misma quien lo tome<\/b> y nadie m\u00e1s estar\u00eda autorizado a administrarlo.<\/p>\n<p class=\"paragraph\">Durante el transcurso del debate, a las puertas del Parlamento se manifestaron este viernes diversas organizaciones, incluidas de personas con discapacidades, tanto a favor como en contra del proyecto legislativo.<\/p>\n<p class=\"paragraph\"><i>(Con informaci\u00f3n de agencias)<\/i><\/p>\n<\/div>\n<p><script defer=\"\">!function(f,b,e,v,n,t,s) {if(f.fbq)return;n=f.fbq=function(){n.callMethod? n.callMethod.apply(n,arguments):n.queue.push(arguments)}; if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0'; n.queue=[];t=b.createElement(e);t.async=!0; t.src=v;s=b.getElementsByTagName(e)[0]; s.parentNode.insertBefore(t,s)}(window, document,'script', ' fbq('init', '336383993555320'); fbq('track', 'PageView'); fbq('track', 'ViewContent');<\/script><script src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js\" crossorigin=\"anonymous\" defer=\"\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara de los Comunes, en Londres (C\u00e1mara de los Comunes\/Parlamento del RU v\u00eda AP\/Archivo) La C\u00e1mara de los Comunes brit\u00e1nica (baja) aprob\u00f3 este viernes, por 330 votos a favor frente a 275 en contra, la proposici\u00f3n de ley planteada por la diputada laborista Kim Leadbeater para legalizar el suicidio asistido en Inglaterra y Gales. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27379,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27378"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=27378"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/27379"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=27378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=27378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=27378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}