{"id":26381,"date":"2024-11-20T11:40:02","date_gmt":"2024-11-20T14:40:02","guid":{"rendered":"https:\/\/maxradio923.com.ar\/index.php\/2024\/11\/20\/acuerdo-bilateral-las-cinco-opciones-que-se-evaluan-para-que-la-argentina-lleve-el-gas-de-vaca-muerta-hasta-brasil\/"},"modified":"2024-11-20T11:40:02","modified_gmt":"2024-11-20T14:40:02","slug":"acuerdo-bilateral-las-cinco-opciones-que-se-evaluan-para-que-la-argentina-lleve-el-gas-de-vaca-muerta-hasta-brasil","status":"publish","type":"post","link":"https:\/\/maxradio923.com.ar\/index.php\/2024\/11\/20\/acuerdo-bilateral-las-cinco-opciones-que-se-evaluan-para-que-la-argentina-lleve-el-gas-de-vaca-muerta-hasta-brasil\/","title":{"rendered":"Acuerdo bilateral: las cinco opciones que se eval\u00faan para que la Argentina lleve el gas de Vaca Muerta hasta Brasil"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\" visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/IZOMAB2JWBNYT476ZDGDS4B3XI.jpg?auth=1349046a7e5d1776b5517b8abc5423182aa6a2526c67e7ddd6772d1906c66306&amp;smart=true&amp;width=992&amp;height=661&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/IZOMAB2JWBNYT476ZDGDS4B3XI.jpg?auth=1349046a7e5d1776b5517b8abc5423182aa6a2526c67e7ddd6772d1906c66306&amp;smart=true&amp;width=768&amp;height=512&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/IZOMAB2JWBNYT476ZDGDS4B3XI.jpg?auth=1349046a7e5d1776b5517b8abc5423182aa6a2526c67e7ddd6772d1906c66306&amp;smart=true&amp;width=577&amp;height=385&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/IZOMAB2JWBNYT476ZDGDS4B3XI.jpg?auth=1349046a7e5d1776b5517b8abc5423182aa6a2526c67e7ddd6772d1906c66306&amp;smart=true&amp;width=420&amp;height=280&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/IZOMAB2JWBNYT476ZDGDS4B3XI.jpg?auth=1349046a7e5d1776b5517b8abc5423182aa6a2526c67e7ddd6772d1906c66306&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"En Brasil esperan que las empresas activen los proyectos para llevar el gas de Vaca Muerta (REUTERS)\" class=\"global-image\" decoding=\"async\" fetchpriority=\"high\" height=\"529\" loading=\"eager\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/IZOMAB2JWBNYT476ZDGDS4B3XI.jpg?auth=1349046a7e5d1776b5517b8abc5423182aa6a2526c67e7ddd6772d1906c66306&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"800\"\/><\/picture><figcaption class=\"article-figcaption-img\">En Brasil esperan que las empresas activen los proyectos para llevar el gas de Vaca Muerta (REUTERS)<\/figcaption><\/div>\n<p class=\"paragraph\">La <b>Argentina<\/b> y<b> Brasil <\/b>firmaron este lunes un acuerdo para trabajar en la viabilidad de que en los pr\u00f3ximos cinco a\u00f1os se puedan alcanzar exportaciones por 30 millones de metros c\u00fabicos diarios de <b>gas natural<\/b> desde <b>Vaca Muerta <\/b>al pa\u00eds vecino. La noticia fue muy bien recibida por el sector energ\u00e9tico por lo que puede ser el convenio comercial m\u00e1s importante de la historia bilateral, aunque solo es el primer paso de un largo camino que deber\u00e1 ser apuntalado por la iniciativa privada.<\/p>\n<p class=\"paragraph\">El grupo de trabajo conformado por representantes de los Gobierno de <b>Javier Milei <\/b>y de <b>Inacio Lula Da Silva<\/b> evaluar\u00e1n cinco rutas que har\u00edan posible los env\u00edos de fluido argentino para abastecer la creciente demanda de la industria brasile\u00f1a:<b> Bolivia, Paraguay, Uruguayana, Uruguay y la venta de gas natural licuado (GNL)<\/b>.<\/p>\n<div class=\" visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/4JV3LJ3IHJFIHJGNQ34FK32CQU.jpg?auth=b869117cfb10ff1de2939859bfd9f9e84ce5e56c12f4ca7b68629fe4fbbcef2c&amp;smart=true&amp;width=992&amp;height=558&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/4JV3LJ3IHJFIHJGNQ34FK32CQU.jpg?auth=b869117cfb10ff1de2939859bfd9f9e84ce5e56c12f4ca7b68629fe4fbbcef2c&amp;smart=true&amp;width=768&amp;height=432&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/4JV3LJ3IHJFIHJGNQ34FK32CQU.jpg?auth=b869117cfb10ff1de2939859bfd9f9e84ce5e56c12f4ca7b68629fe4fbbcef2c&amp;smart=true&amp;width=577&amp;height=325&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/4JV3LJ3IHJFIHJGNQ34FK32CQU.jpg?auth=b869117cfb10ff1de2939859bfd9f9e84ce5e56c12f4ca7b68629fe4fbbcef2c&amp;smart=true&amp;width=420&amp;height=236&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/4JV3LJ3IHJFIHJGNQ34FK32CQU.jpg?auth=b869117cfb10ff1de2939859bfd9f9e84ce5e56c12f4ca7b68629fe4fbbcef2c&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"Infograf\u00eda oficial del Ministerio de Minas y Energ\u00eda de Brasil\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"1080\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/4JV3LJ3IHJFIHJGNQ34FK32CQU.jpg?auth=b869117cfb10ff1de2939859bfd9f9e84ce5e56c12f4ca7b68629fe4fbbcef2c&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" width=\"1920\"\/><\/picture><figcaption class=\"article-figcaption-img\">Infograf\u00eda oficial del Ministerio de Minas y Energ\u00eda de Brasil<\/figcaption><\/div>\n<p class=\"paragraph\">La opci\u00f3n que en el mercado miran como la <b>m\u00e1s r\u00e1pida <\/b>es la de aprovechar la infraestructura del <b>Gasoducto Brasil Bolivia (Gasbol)<\/b>, en medio del declino que sufre la industria boliviana tras a\u00f1os de desinversi\u00f3n. El ducto puede transportar unos 30 millones de metros c\u00fabicos diarios y actualmente funciona en torno a los 10 millones, es decir, a un tercio de su capacidad.<\/p>\n<p class=\"paragraph\">Pero para conseguir llegar a ese objetivo no alcanza con la primera etapa de Reversi\u00f3n del Gasoducto Norte, inaugurada hace unas semanas, que permitir\u00e1 conectar Vaca Muerta con siete provincias del norte argentino (<b>C\u00f3rdoba, Tucum\u00e1n, La Rioja, Catamarca, Santiago del Estero, Salta y Jujuy<\/b>) para transportar hasta all\u00ed unos 19 millones de metros c\u00fabicos por d\u00eda.<\/p>\n<p class=\"paragraph\">Es necesario encarar una segunda etapa con<i> loops<\/i> (ducto paralelo) y plantas compresoras para conseguir un excedente m\u00ednimo de 15 millones de metros c\u00fabicos que al menos tardar\u00eda hasta 2026. Tambi\u00e9n se necesita negociar con Bolivia una tarifa para utilizar sus gasoductos que permita que el fluido llegue a Brasil a un precio competitivo.<\/p>\n<p class=\"paragraph\">El Gobierno brasile\u00f1o aspira a conseguir \u201cgas barato\u201d para alimentar y hacer m\u00e1s competitiva su industria, en l\u00ednea con lo que explic\u00f3 el ministro de Minas y Energ\u00eda brasile\u00f1o,<b> Alexander Silveira<\/b>, tras la firma del <b>Memorando de Entendimiento (MOU) <\/b>con el ministro de Econom\u00eda argentino, <b>Luis Caputo<\/b>, en el marco de la cumbre del G20 que se celebr\u00f3 en R\u00edo de Janeiro.<\/p>\n<p class=\"paragraph\">La otra posibilidad es la de Paraguay, que se mostr\u00f3 dispuesto a sumar financiamiento para un proyecto de USD 1.500 millones que lleve 15 millones de metros c\u00fabicos d\u00eda que comience en Salta y llegue a Campo Grande en el suroeste de Brasil.<\/p>\n<div class=\" visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/2M3JMDGBUBFZ3J3SOQW64O2M7M.jpg?auth=a39efbe906e4f65a25b2e777a86ee54690ed34c52fabd09220b61b4c27ec9dda&amp;smart=true&amp;width=992&amp;height=558&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/2M3JMDGBUBFZ3J3SOQW64O2M7M.jpg?auth=a39efbe906e4f65a25b2e777a86ee54690ed34c52fabd09220b61b4c27ec9dda&amp;smart=true&amp;width=768&amp;height=432&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/2M3JMDGBUBFZ3J3SOQW64O2M7M.jpg?auth=a39efbe906e4f65a25b2e777a86ee54690ed34c52fabd09220b61b4c27ec9dda&amp;smart=true&amp;width=577&amp;height=325&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/2M3JMDGBUBFZ3J3SOQW64O2M7M.jpg?auth=a39efbe906e4f65a25b2e777a86ee54690ed34c52fabd09220b61b4c27ec9dda&amp;smart=true&amp;width=420&amp;height=236&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/2M3JMDGBUBFZ3J3SOQW64O2M7M.jpg?auth=a39efbe906e4f65a25b2e777a86ee54690ed34c52fabd09220b61b4c27ec9dda&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"Momento en el que se firm\u00f3 el MOU\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"1080\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/2M3JMDGBUBFZ3J3SOQW64O2M7M.jpg?auth=a39efbe906e4f65a25b2e777a86ee54690ed34c52fabd09220b61b4c27ec9dda&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" width=\"1920\"\/><\/picture><figcaption class=\"article-figcaption-img\">Momento en el que se firm\u00f3 el MOU<\/figcaption><\/div>\n<p class=\"paragraph\">Por otro lado, se encuentran la posibilidad de pasar a Rio Grande do Sul, Santa Catarina y Paran\u00e1. Primero es necesario que se avance en la segunda etapa del <b>Gasoducto Perito Francisco Pascasio Moreno <\/b>(ex Presidente N\u00e9stor Kirchner) que conecta Tratayen (Neuqu\u00e9n) con Salliquel\u00f3 (Buenos Aires). A estos se sumar\u00eda un ducto por Uruguayana para llegar a Porto Alegre.<\/p>\n<p class=\"paragraph\">Otra alternativa de gasoducto ser\u00eda utilizar el paso por Uruguay a trav\u00e9s del Gasoducto Cruz del Sur que une Punta Lara con Colonia. All\u00ed har\u00eda falta la construcci\u00f3n de un tramo de ca\u00f1o desde Montevideo a Porto Alegre y nuevas plantas compresoras para sumar capacidad.<\/p>\n<p class=\"paragraph\">La \u00faltima opci\u00f3n es que la Argentina le venda a Brasil GNL a partir de proyectos que tienen en carpeta empresas que operan localmente. El proyecto que pica en punta es la barcaza de licuefacci\u00f3n que instalar\u00e1n en R\u00edo Negro<b> <\/b><b>Pan American Energy (PAE) <\/b>y la noruega <b>Golar<\/b> para exportar 11,5 millones de metros c\u00fabicos diarios a partir de 2027. All\u00ed podr\u00edan sumarse otros jugadores, como es el caso de la estatal <b>YPF.<\/b><\/p>\n<p class=\"paragraph\">Por su parte, la petrolera estatal planea construir una planta de licuefacci\u00f3n en Punta Colorada, R\u00edo Negro, pero para poder exportar GNL reci\u00e9n desde 2031 seg\u00fan el objetivo de la compa\u00f1\u00eda de mayor\u00eda estatal. El presidente de la firma, <b>Horacio Mar\u00edn<\/b>, anticip\u00f3 que el proyecto se llevar\u00e1 adelante m\u00e1s all\u00e1 de que participe o no la malaya<b> Petronas<\/b>, tal como se preve\u00eda originalmente.<\/p>\n<div class=\" visual__image\"><picture><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/YB52TAIWX5FLFJR4C2TA4JU7CQ.jpg?auth=d9c17f26b19868e9d589566782a5422cc19eddeb65ceeb6b09290b0e8f459f00&amp;smart=true&amp;width=992&amp;height=558&amp;quality=85\" media=\"(min-width: 1000px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/YB52TAIWX5FLFJR4C2TA4JU7CQ.jpg?auth=d9c17f26b19868e9d589566782a5422cc19eddeb65ceeb6b09290b0e8f459f00&amp;smart=true&amp;width=768&amp;height=432&amp;quality=85\" media=\"(min-width: 768px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/YB52TAIWX5FLFJR4C2TA4JU7CQ.jpg?auth=d9c17f26b19868e9d589566782a5422cc19eddeb65ceeb6b09290b0e8f459f00&amp;smart=true&amp;width=577&amp;height=325&amp;quality=85\" media=\"(min-width: 580px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/YB52TAIWX5FLFJR4C2TA4JU7CQ.jpg?auth=d9c17f26b19868e9d589566782a5422cc19eddeb65ceeb6b09290b0e8f459f00&amp;smart=true&amp;width=420&amp;height=236&amp;quality=85\" media=\"(min-width: 350px)\"\/><source srcset=\"https:\/\/www.infobae.com\/resizer\/v2\/YB52TAIWX5FLFJR4C2TA4JU7CQ.jpg?auth=d9c17f26b19868e9d589566782a5422cc19eddeb65ceeb6b09290b0e8f459f00&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" media=\"(min-width: 80px)\"\/><img alt=\"Buque de licuefacci\u00f3n \u201cHilli Episeyo\u201d con el que PAE y Golar producir\u00e1n GNL para exportar desde 2027\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"1080\" loading=\"lazy\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/YB52TAIWX5FLFJR4C2TA4JU7CQ.jpg?auth=d9c17f26b19868e9d589566782a5422cc19eddeb65ceeb6b09290b0e8f459f00&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" width=\"1920\"\/><\/picture><figcaption class=\"article-figcaption-img\">Buque de licuefacci\u00f3n \u201cHilli Episeyo\u201d con el que PAE y Golar producir\u00e1n GNL para exportar desde 2027<\/figcaption><\/div>\n<p class=\"paragraph\">El MOU firmado entre ambos pa\u00edses contempla la creaci\u00f3n de una mesa de trabajo para discutir las alternativas para llegar al objetivo de exportaciones por 30 millones de metros c\u00fabicos diarios en los pr\u00f3ximos cinco a\u00f1os. Se espera que a partir de 2025 comenzar\u00e1n env\u00edos por 2 millones de metros c\u00fabicos, que crecer\u00e1 a 10 millones en tres a\u00f1os y llegar\u00eda finalmente a los 30 millones.<\/p>\n<p class=\"paragraph\">El Gobierno argentino resalt\u00f3 en varias oportunidades que las futuras grandes obras de infraestructura no tendr\u00e1n financiamiento p\u00fablico, sino que deber\u00e1n ser impulsadas por el sector privado. La gran apuesta es el <b>R\u00e9gimen de Incentivo a las Grandes Inversiones (RIGI)<\/b>, el esquema de beneficios impositivos y cambiarios para proyectos que demanden desde USD 200 millones impulsado por la gesti\u00f3n Milei.<\/p>\n<p class=\"paragraph\">Para la Argentina la venta de gas a Brasil resultar\u00eda una posibilidad \u00fanica para generar divisas ante un abultado cronograma de vencimientos de deuda en los pr\u00f3ximos a\u00f1os y equilibrar una balanza comercial que ahora es deficitaria. Para los brasile\u00f1os puede significar energ\u00eda barata para abastecer la creciente demanda industrial del sur y la posibilidad de producir fertilizantes a precio competitivo.<\/p>\n<\/div>\n<p><script defer=\"\">!function(f,b,e,v,n,t,s) {if(f.fbq)return;n=f.fbq=function(){n.callMethod? n.callMethod.apply(n,arguments):n.queue.push(arguments)}; if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0'; n.queue=[];t=b.createElement(e);t.async=!0; t.src=v;s=b.getElementsByTagName(e)[0]; s.parentNode.insertBefore(t,s)}(window, document,'script', ' fbq('init', '336383993555320'); fbq('track', 'PageView'); fbq('track', 'ViewContent');<\/script><script src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js\" crossorigin=\"anonymous\" defer=\"\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Brasil esperan que las empresas activen los proyectos para llevar el gas de Vaca Muerta (REUTERS) La Argentina y Brasil firmaron este lunes un acuerdo para trabajar en la viabilidad de que en los pr\u00f3ximos cinco a\u00f1os se puedan alcanzar exportaciones por 30 millones de metros c\u00fabicos diarios de gas natural desde Vaca Muerta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26382,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/26381"}],"collection":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=26381"}],"version-history":[{"count":0,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/26381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media\/26382"}],"wp:attachment":[{"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=26381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=26381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxradio923.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=26381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}